{"id":15700,"date":"2018-03-20T06:30:51","date_gmt":"2018-03-20T06:30:51","guid":{"rendered":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2018\/03\/20\/4mila-giovani-esclusi-da-psr-risorse-da-gal-e-da-misure-improduttive\/"},"modified":"2018-03-20T06:30:51","modified_gmt":"2018-03-20T06:30:51","slug":"4mila-giovani-esclusi-da-psr-risorse-da-gal-e-da-misure-improduttive","status":"publish","type":"post","link":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2018\/03\/20\/4mila-giovani-esclusi-da-psr-risorse-da-gal-e-da-misure-improduttive\/","title":{"rendered":"4mila giovani esclusi da Psr, risorse da Gal e da misure improduttive"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-15697\" src=\"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2018\/03\/m_IMG_2561.jpg\" alt=\"m IMG 2561\" style=\"margin-right: 2px; margin-left: 2px;\" height=\"150\" width=\"320\" \/><\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Migliaia di giovani provenienti da tutta la Puglia si sono dati appuntamento con l\u2019hashtag&nbsp;<i>#bandiallosbando&nbsp;<\/i>sotto il \u2018palazzo del potere\u2019, l\u2019Assessorato all\u2019Agricoltura della Regione Puglia, con cartelli, striscioni, gi\u00e0 pronti a partire con valigie e zaini alla mano, perch\u00e9 costretti a cambiare Nazione e mestiere. L\u2019iniziativa \u00e8 di Coldiretti Puglia, perch\u00e9 dopo 2 anni dalla pubblicazione del bando per l\u2019insediamento dei giovani in agricoltura, sono solo 1000 le domande finanziabili, un tradimento delle aspettative dell\u2019esercito di giovani che vogliono investire in un settore considerato fino a pochi anni fa vecchio&nbsp;e&nbsp;senza prospettive,&nbsp;come si legge su cartelli e striscioni \u2018gi\u00f9 le mani dal nostro futuro\u2019, \u2018Giovani in campo per il futuro della Puglia\u2019, \u2018AAA bando PSR cercasi\u2019, \u2018Emiliano aiutaci tu blocca la politica politicante\u2019, \u2018Emiliano blocca la fuga di cervelli\u2019.&nbsp;&nbsp;<\/p>\n<p style=\"text-align: justify;\">\u201cSono 4mila i giovani esclusi dal PSR per la mancanza di risorse e la gestione delle misure \u2013 spiega il Presidente di Coldiretti Puglia, Gianni Cantele \u2013 che aspettano risposte concrete. Vanno immediatamente recuperate risorse da misure improduttive e soprattutto dai GAL (Gruppi di Azione Locale). In caso contrario la Regione dovr\u00e0 assumersi la responsabilit\u00e0 di spiegare ai giovani che intendono investire in agricoltura perch\u00e9 a loro sono stati destinati solo 100 milioni di euro. Viceversa sono stati destinati 158 milioni ai 23 GAL, ossia in una misura in cui circa il 20% dell&#8217;importo totale &#8211; oltre 30 milioni di euro &#8211; pu\u00f2 essere rendicontato per spese generali. Si finanziano cos\u00ec apparati burocratici e collaboratori di varia provenienza, superando tutte le distinzioni fra politica ed amministrazione&nbsp;e&nbsp;sottraendo risorse ai giovani agricoltori\u201d.<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-15698\" src=\"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2018\/03\/m_IMG_2550.jpg\" alt=\"m IMG 2550\" style=\"margin-right: 2px; margin-left: 2px;\" width=\"450\" height=\"600\" srcset=\"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2018\/03\/m_IMG_2550.jpg 450w, https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2018\/03\/m_IMG_2550-225x300.jpg 225w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/p>\n<p style=\"text-align: justify;\">A seguito dell\u2019apertura del bando e alla presentazione di diversi ricorsi al TAR, la Regione ha deciso di approvare tutti i 23 GAL presentati, ricorda ancora Coldiretti Puglia. &nbsp;<\/p>\n<p style=\"text-align: justify;\">\u201cLa Puglia \u00e8 la regione con un numero spropositato di GAL, come abbiamo sempre denunciato \u2013 aggiunge il Direttore di Coldiretti Puglia, Angelo Corsetti \u2013 ben 23, contro 12 della Lombardia, 14 del Piemonte, 7 della Toscana, 6 dell\u2019Emilia Romagna, solo per citare alcuni esempi. Ai 23 GAL \u00e8 stato destinato il 9,8% delle risorse del PSR, una scelta che ha causato il taglio &nbsp;di risorse sulle misure di cui gli agricoltori sono direttamente beneficiari, come le misure per investimenti, pacchetto giovani e misure ambientali. Se la Regione destinasse una percentuale massima di risorse pari al 5% (percentuale minima imposta dall\u2019UE), come richiesto da Coldiretti Puglia, sarebbero liberati circa 80 milioni di euro, da poter destinare alla Misura giovani. Ci\u00f2 consentirebbe l\u2019ingresso in agricoltura di circa 1.500 giovani in pi\u00f9, dando risposte a parte dei 4mila giovani oggi esclusi dal PSR\u201d.<\/p>\n<p style=\"text-align: justify;\">L\u2019Unione Europea ha imposto il 5% delle risorse dei PSR ai GAL e la Puglia ha fatto la scelta politica di andare oltre assegnando alla misura dei GAL pi\u00f9 risorse della misura giovani. Oggi l\u2019esclusione di 4mila giovani dai finanziamenti \u2013 conclude Coldiretti Puglia \u2013 impone di rivedere la scelta, per fare in modo che le risorse comunitarie del PSR Puglia siano spesi in maniera coerente e corretta a beneficio del territorio, dell\u2019imprenditoria agricola pugliese e dell\u2019innovazione in atto.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-15699\" src=\"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2018\/03\/m_IMG_2573.jpg\" alt=\"m IMG 2573\" style=\"margin-right: 2px; margin-left: 2px;\" width=\"600\" height=\"450\" srcset=\"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2018\/03\/m_IMG_2573.jpg 600w, https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2018\/03\/m_IMG_2573-300x225.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":15697,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[13],"tags":[],"class_list":["post-15700","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>4mila giovani esclusi da Psr, risorse da Gal e da misure improduttive - Archivio CassanoWeb<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2018\/03\/20\/4mila-giovani-esclusi-da-psr-risorse-da-gal-e-da-misure-improduttive\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"4mila giovani esclusi da Psr, risorse da Gal e da misure improduttive - Archivio CassanoWeb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2018\/03\/20\/4mila-giovani-esclusi-da-psr-risorse-da-gal-e-da-misure-improduttive\/\" \/>\n<meta property=\"og:site_name\" content=\"Archivio CassanoWeb\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/redazione.cassanoweb\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-20T06:30:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2018\/03\/m_IMG_2561.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2018\\\/03\\\/20\\\/4mila-giovani-esclusi-da-psr-risorse-da-gal-e-da-misure-improduttive\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2018\\\/03\\\/20\\\/4mila-giovani-esclusi-da-psr-risorse-da-gal-e-da-misure-improduttive\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#\\\/schema\\\/person\\\/df195bc79a9b4c35127cf005f92e041b\"},\"headline\":\"4mila giovani esclusi da Psr, risorse da Gal e da misure improduttive\",\"datePublished\":\"2018-03-20T06:30:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2018\\\/03\\\/20\\\/4mila-giovani-esclusi-da-psr-risorse-da-gal-e-da-misure-improduttive\\\/\"},\"wordCount\":523,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2018\\\/03\\\/20\\\/4mila-giovani-esclusi-da-psr-risorse-da-gal-e-da-misure-improduttive\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/m_IMG_2561.jpg\",\"articleSection\":[\"Economia\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2018\\\/03\\\/20\\\/4mila-giovani-esclusi-da-psr-risorse-da-gal-e-da-misure-improduttive\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2018\\\/03\\\/20\\\/4mila-giovani-esclusi-da-psr-risorse-da-gal-e-da-misure-improduttive\\\/\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2018\\\/03\\\/20\\\/4mila-giovani-esclusi-da-psr-risorse-da-gal-e-da-misure-improduttive\\\/\",\"name\":\"4mila giovani esclusi da Psr, risorse da Gal e da misure improduttive - Archivio CassanoWeb\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2018\\\/03\\\/20\\\/4mila-giovani-esclusi-da-psr-risorse-da-gal-e-da-misure-improduttive\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2018\\\/03\\\/20\\\/4mila-giovani-esclusi-da-psr-risorse-da-gal-e-da-misure-improduttive\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/m_IMG_2561.jpg\",\"datePublished\":\"2018-03-20T06:30:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2018\\\/03\\\/20\\\/4mila-giovani-esclusi-da-psr-risorse-da-gal-e-da-misure-improduttive\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2018\\\/03\\\/20\\\/4mila-giovani-esclusi-da-psr-risorse-da-gal-e-da-misure-improduttive\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2018\\\/03\\\/20\\\/4mila-giovani-esclusi-da-psr-risorse-da-gal-e-da-misure-improduttive\\\/#primaryimage\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/m_IMG_2561.jpg\",\"contentUrl\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/m_IMG_2561.jpg\",\"width\":600,\"height\":450,\"caption\":\"m IMG 2561\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2018\\\/03\\\/20\\\/4mila-giovani-esclusi-da-psr-risorse-da-gal-e-da-misure-improduttive\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"4mila giovani esclusi da Psr, risorse da Gal e da misure improduttive\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#website\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/\",\"name\":\"Archivio CassanoWeb\",\"description\":\"La Voce del Paese - un network di idee\",\"publisher\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#organization\",\"name\":\"Archivio CassanoWeb\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/logo-rosso-2.png\",\"contentUrl\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/logo-rosso-2.png\",\"width\":491,\"height\":432,\"caption\":\"Archivio CassanoWeb\"},\"image\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/redazione.cassanoweb\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#\\\/schema\\\/person\\\/df195bc79a9b4c35127cf005f92e041b\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\"],\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/author\\\/admin_0qgz1xdp\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"4mila giovani esclusi da Psr, risorse da Gal e da misure improduttive - Archivio CassanoWeb","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2018\/03\/20\/4mila-giovani-esclusi-da-psr-risorse-da-gal-e-da-misure-improduttive\/","og_locale":"it_IT","og_type":"article","og_title":"4mila giovani esclusi da Psr, risorse da Gal e da misure improduttive - Archivio CassanoWeb","og_url":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2018\/03\/20\/4mila-giovani-esclusi-da-psr-risorse-da-gal-e-da-misure-improduttive\/","og_site_name":"Archivio CassanoWeb","article_publisher":"https:\/\/www.facebook.com\/redazione.cassanoweb","article_published_time":"2018-03-20T06:30:51+00:00","og_image":[{"width":600,"height":450,"url":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2018\/03\/m_IMG_2561.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"admin","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2018\/03\/20\/4mila-giovani-esclusi-da-psr-risorse-da-gal-e-da-misure-improduttive\/#article","isPartOf":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2018\/03\/20\/4mila-giovani-esclusi-da-psr-risorse-da-gal-e-da-misure-improduttive\/"},"author":{"name":"admin","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#\/schema\/person\/df195bc79a9b4c35127cf005f92e041b"},"headline":"4mila giovani esclusi da Psr, risorse da Gal e da misure improduttive","datePublished":"2018-03-20T06:30:51+00:00","mainEntityOfPage":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2018\/03\/20\/4mila-giovani-esclusi-da-psr-risorse-da-gal-e-da-misure-improduttive\/"},"wordCount":523,"commentCount":0,"publisher":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#organization"},"image":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2018\/03\/20\/4mila-giovani-esclusi-da-psr-risorse-da-gal-e-da-misure-improduttive\/#primaryimage"},"thumbnailUrl":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2018\/03\/m_IMG_2561.jpg","articleSection":["Economia"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2018\/03\/20\/4mila-giovani-esclusi-da-psr-risorse-da-gal-e-da-misure-improduttive\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2018\/03\/20\/4mila-giovani-esclusi-da-psr-risorse-da-gal-e-da-misure-improduttive\/","url":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2018\/03\/20\/4mila-giovani-esclusi-da-psr-risorse-da-gal-e-da-misure-improduttive\/","name":"4mila giovani esclusi da Psr, risorse da Gal e da misure improduttive - Archivio CassanoWeb","isPartOf":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2018\/03\/20\/4mila-giovani-esclusi-da-psr-risorse-da-gal-e-da-misure-improduttive\/#primaryimage"},"image":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2018\/03\/20\/4mila-giovani-esclusi-da-psr-risorse-da-gal-e-da-misure-improduttive\/#primaryimage"},"thumbnailUrl":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2018\/03\/m_IMG_2561.jpg","datePublished":"2018-03-20T06:30:51+00:00","breadcrumb":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2018\/03\/20\/4mila-giovani-esclusi-da-psr-risorse-da-gal-e-da-misure-improduttive\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2018\/03\/20\/4mila-giovani-esclusi-da-psr-risorse-da-gal-e-da-misure-improduttive\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2018\/03\/20\/4mila-giovani-esclusi-da-psr-risorse-da-gal-e-da-misure-improduttive\/#primaryimage","url":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2018\/03\/m_IMG_2561.jpg","contentUrl":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2018\/03\/m_IMG_2561.jpg","width":600,"height":450,"caption":"m IMG 2561"},{"@type":"BreadcrumbList","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2018\/03\/20\/4mila-giovani-esclusi-da-psr-risorse-da-gal-e-da-misure-improduttive\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/archiviocassano.lavocedelpaese.info\/"},{"@type":"ListItem","position":2,"name":"4mila giovani esclusi da Psr, risorse da Gal e da misure improduttive"}]},{"@type":"WebSite","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#website","url":"https:\/\/archiviocassano.lavocedelpaese.info\/","name":"Archivio CassanoWeb","description":"La Voce del Paese - un network di idee","publisher":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/archiviocassano.lavocedelpaese.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#organization","name":"Archivio CassanoWeb","url":"https:\/\/archiviocassano.lavocedelpaese.info\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#\/schema\/logo\/image\/","url":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2024\/08\/logo-rosso-2.png","contentUrl":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2024\/08\/logo-rosso-2.png","width":491,"height":432,"caption":"Archivio CassanoWeb"},"image":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/redazione.cassanoweb"]},{"@type":"Person","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#\/schema\/person\/df195bc79a9b4c35127cf005f92e041b","name":"admin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/archiviocassano.lavocedelpaese.info"],"url":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/author\/admin_0qgz1xdp\/"}]}},"_links":{"self":[{"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/15700","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/comments?post=15700"}],"version-history":[{"count":0,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/15700\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/media\/15697"}],"wp:attachment":[{"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/media?parent=15700"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/categories?post=15700"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/tags?post=15700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}