{"id":17847,"date":"2019-08-09T06:04:38","date_gmt":"2019-08-09T06:04:38","guid":{"rendered":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2019\/08\/09\/stasera-sul-piazzale-del-convento-qaspettando-san-lorenzoq\/"},"modified":"2019-08-09T06:04:38","modified_gmt":"2019-08-09T06:04:38","slug":"stasera-sul-piazzale-del-convento-qaspettando-san-lorenzoq","status":"publish","type":"post","link":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2019\/08\/09\/stasera-sul-piazzale-del-convento-qaspettando-san-lorenzoq\/","title":{"rendered":"Stasera sul piazzale del Convento &#8220;Aspettando san Lorenzo&#8221;"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-17846\" src=\"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2019\/08\/67703553_1328946893935737_5781625643749867520_n.jpg\" width=\"320\" height=\"150\" alt=\"67703553 1328946893935737 5781625643749867520 n\" style=\"margin-right: 2px; margin-left: 2px;\" \/><\/p>\n<p><!--more--><\/p>\n<p>&nbsp;&#8220;Se esprimi un desiderio \u00e8 perch\u00e9 vedi cadere una stella, se vedi cadere una stella \u00e8 perch\u00e9 stai guardando il cielo, se stai guardando il cielo \u00e8 perch\u00e9 credi ancora in qualcosa&#8221;.<\/p>\n<p>Nelle parole di Bob Marley, il senso della notte di San Lorenzo!<\/p>\n<p>L&#8217;occasione ideale per guardare il cielo e credere che, alla vista di una scia luminosa, tutti i desideri possano diventare realt\u00e0.<\/p>\n<p>&#8220;Lo faremo insieme &#8211; scrive in una nota la Pro Loco &#8220;La Murgianella&#8221; &#8211; venerd\u00ec 9 agosto a partire dalle 21.30, sul Piazzale del Santuario Convento di Cassano delle Murge, con ASPETTANDO SAN LORENZO! Evento reso possibile anche grazie alla collaborazione di<a href=\"https:\/\/www.facebook.com\/dominusosteria\/?__xts__%5B0%5D=68.ARA0ioaGaRBN-afqV7-IAPS3-s-W9Y3LxjYTuQ8c-OXhekr4Gqn6ThVBJF-AEyyOY2Ex7JqfoTIGu6CgzGUKLmqlGlEnf57-RkBNxshHFkvLwsnZQS45Y7Io5LnTGgvF8FFamlYKSsdo-mKV0BEVclNz0Kzytj_IFUSoq0WEa5mlTYqeaeLd8jGWuy9RmdU9cuwSRlEb7DZi2fwhDn2pSMFIIxcAdfR3CE1LAVsq95HaO--zloTN5JnLuawiVN8FyqTGfJ9oCENhqUCFnAxtPX31I4Dy8YlDk60pJO90ZFQJLt3nHfW82Na154-fLpJiZB-qqcZcp5LFduiqCYQHXpQyx4GQDvnT4OcTpoC8pi_74VTF4D-F-qk&amp;__xts__%5B1%5D=68.ARAOR6dXHGliJ8PLhlD8M5dluFqFNh_ys3e4gA99rnh2H8B2eX4eqENXtJSSsAEtMGIxQPXL1hMX3xqE9W9iE_Z3E2D9Ope8AgPhgIus29t7x9UTxaAAKDK2npP03K4ILhvWX-0y-k3XYCw4PzInHQ73TVD9aWlm1skn8hE-8B2uGzwKKQ3eoqhbwGTDY2wpm5_3XoWacW6z6DSkgmuDsI1AnymT590Wr7n9L9vVbAEc3EGlJbj5zK0v7b_lezj6jWUTqU54eeXKH5JKiqU4lgproTy10iv9RxkVZ2RpUrkSNNGnG8ipDWo7WwrYcxEObuuE8xCTZ1icLCEu1LIsVJHljr75aV2CcTcXsTuuEG3m2FtvXye_R3Pjt4YpD6IgRyEw&amp;__tn__=K%2AF&amp;eid=ARBTg4_ZVkzDwjzSFHY9QxOiQmssEQbWINWsarGsMTOiQV5bHEs55s58NpJ-4ZhyjlC3xsvHp_W62Kru\" data-hovercard=\"\/ajax\/hovercard\/page.php?id=107916472586504&amp;extragetparams=%7B%22__tn__%22%3A%22%2CdK%2AF-R%22%2C%22eid%22%3A%22ARBTg4_ZVkzDwjzSFHY9QxOiQmssEQbWINWsarGsMTOiQV5bHEs55s58NpJ-4ZhyjlC3xsvHp_W62Kru%22%2C%22directed_target_id%22%3Anull%2C%22groups_location%22%3Anull%7D\" data-hovercard-prefer-more-content-show=\"1\">Dominus Osteria<\/a>.<\/p>\n<p>Con noi ci saranno gli&nbsp;<a href=\"https:\/\/www.facebook.com\/EndlessRiverTributeBand\/?__xts__%5B0%5D=68.ARA0ioaGaRBN-afqV7-IAPS3-s-W9Y3LxjYTuQ8c-OXhekr4Gqn6ThVBJF-AEyyOY2Ex7JqfoTIGu6CgzGUKLmqlGlEnf57-RkBNxshHFkvLwsnZQS45Y7Io5LnTGgvF8FFamlYKSsdo-mKV0BEVclNz0Kzytj_IFUSoq0WEa5mlTYqeaeLd8jGWuy9RmdU9cuwSRlEb7DZi2fwhDn2pSMFIIxcAdfR3CE1LAVsq95HaO--zloTN5JnLuawiVN8FyqTGfJ9oCENhqUCFnAxtPX31I4Dy8YlDk60pJO90ZFQJLt3nHfW82Na154-fLpJiZB-qqcZcp5LFduiqCYQHXpQyx4GQDvnT4OcTpoC8pi_74VTF4D-F-qk&amp;__xts__%5B1%5D=68.ARAOR6dXHGliJ8PLhlD8M5dluFqFNh_ys3e4gA99rnh2H8B2eX4eqENXtJSSsAEtMGIxQPXL1hMX3xqE9W9iE_Z3E2D9Ope8AgPhgIus29t7x9UTxaAAKDK2npP03K4ILhvWX-0y-k3XYCw4PzInHQ73TVD9aWlm1skn8hE-8B2uGzwKKQ3eoqhbwGTDY2wpm5_3XoWacW6z6DSkgmuDsI1AnymT590Wr7n9L9vVbAEc3EGlJbj5zK0v7b_lezj6jWUTqU54eeXKH5JKiqU4lgproTy10iv9RxkVZ2RpUrkSNNGnG8ipDWo7WwrYcxEObuuE8xCTZ1icLCEu1LIsVJHljr75aV2CcTcXsTuuEG3m2FtvXye_R3Pjt4YpD6IgRyEw&amp;__tn__=K%2AF&amp;eid=ARB871kYz1X_vHElUiUAbNX-aN3bXjqGg3NNmY-84hl98xTjPrcOzhUauQzf3gKjeNO232xg9xHPVGtp\" data-hovercard=\"\/ajax\/hovercard\/page.php?id=356257914578839&amp;extragetparams=%7B%22__tn__%22%3A%22%2CdK%2AF-R%22%2C%22eid%22%3A%22ARB871kYz1X_vHElUiUAbNX-aN3bXjqGg3NNmY-84hl98xTjPrcOzhUauQzf3gKjeNO232xg9xHPVGtp%22%2C%22directed_target_id%22%3Anull%2C%22groups_location%22%3Anull%7D\" data-hovercard-prefer-more-content-show=\"1\">Endless River &#8211; Pink Floyd tribute band<\/a>, per una serata ancor pi\u00f9 magica!&#8221;<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":17846,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[11],"tags":[],"class_list":["post-17847","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-appuntamenti"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Stasera sul piazzale del Convento &quot;Aspettando san Lorenzo&quot; - Archivio CassanoWeb<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2019\/08\/09\/stasera-sul-piazzale-del-convento-qaspettando-san-lorenzoq\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Stasera sul piazzale del Convento &quot;Aspettando san Lorenzo&quot; - Archivio CassanoWeb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2019\/08\/09\/stasera-sul-piazzale-del-convento-qaspettando-san-lorenzoq\/\" \/>\n<meta property=\"og:site_name\" content=\"Archivio CassanoWeb\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/redazione.cassanoweb\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-09T06:04:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2019\/08\/67703553_1328946893935737_5781625643749867520_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"540\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2019\\\/08\\\/09\\\/stasera-sul-piazzale-del-convento-qaspettando-san-lorenzoq\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2019\\\/08\\\/09\\\/stasera-sul-piazzale-del-convento-qaspettando-san-lorenzoq\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#\\\/schema\\\/person\\\/df195bc79a9b4c35127cf005f92e041b\"},\"headline\":\"Stasera sul piazzale del Convento &#8220;Aspettando san Lorenzo&#8221;\",\"datePublished\":\"2019-08-09T06:04:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2019\\\/08\\\/09\\\/stasera-sul-piazzale-del-convento-qaspettando-san-lorenzoq\\\/\"},\"wordCount\":132,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2019\\\/08\\\/09\\\/stasera-sul-piazzale-del-convento-qaspettando-san-lorenzoq\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/67703553_1328946893935737_5781625643749867520_n.jpg\",\"articleSection\":[\"Appuntamenti\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2019\\\/08\\\/09\\\/stasera-sul-piazzale-del-convento-qaspettando-san-lorenzoq\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2019\\\/08\\\/09\\\/stasera-sul-piazzale-del-convento-qaspettando-san-lorenzoq\\\/\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2019\\\/08\\\/09\\\/stasera-sul-piazzale-del-convento-qaspettando-san-lorenzoq\\\/\",\"name\":\"Stasera sul piazzale del Convento \\\"Aspettando san Lorenzo\\\" - Archivio CassanoWeb\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2019\\\/08\\\/09\\\/stasera-sul-piazzale-del-convento-qaspettando-san-lorenzoq\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2019\\\/08\\\/09\\\/stasera-sul-piazzale-del-convento-qaspettando-san-lorenzoq\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/67703553_1328946893935737_5781625643749867520_n.jpg\",\"datePublished\":\"2019-08-09T06:04:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2019\\\/08\\\/09\\\/stasera-sul-piazzale-del-convento-qaspettando-san-lorenzoq\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2019\\\/08\\\/09\\\/stasera-sul-piazzale-del-convento-qaspettando-san-lorenzoq\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2019\\\/08\\\/09\\\/stasera-sul-piazzale-del-convento-qaspettando-san-lorenzoq\\\/#primaryimage\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/67703553_1328946893935737_5781625643749867520_n.jpg\",\"contentUrl\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/67703553_1328946893935737_5781625643749867520_n.jpg\",\"width\":960,\"height\":540,\"caption\":\"67703553 1328946893935737 5781625643749867520 n\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2019\\\/08\\\/09\\\/stasera-sul-piazzale-del-convento-qaspettando-san-lorenzoq\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Stasera sul piazzale del Convento &#8220;Aspettando san Lorenzo&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#website\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/\",\"name\":\"Archivio CassanoWeb\",\"description\":\"La Voce del Paese - un network di idee\",\"publisher\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#organization\",\"name\":\"Archivio CassanoWeb\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/logo-rosso-2.png\",\"contentUrl\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/logo-rosso-2.png\",\"width\":491,\"height\":432,\"caption\":\"Archivio CassanoWeb\"},\"image\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/redazione.cassanoweb\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#\\\/schema\\\/person\\\/df195bc79a9b4c35127cf005f92e041b\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\"],\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/author\\\/admin_0qgz1xdp\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Stasera sul piazzale del Convento \"Aspettando san Lorenzo\" - Archivio CassanoWeb","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2019\/08\/09\/stasera-sul-piazzale-del-convento-qaspettando-san-lorenzoq\/","og_locale":"it_IT","og_type":"article","og_title":"Stasera sul piazzale del Convento \"Aspettando san Lorenzo\" - Archivio CassanoWeb","og_url":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2019\/08\/09\/stasera-sul-piazzale-del-convento-qaspettando-san-lorenzoq\/","og_site_name":"Archivio CassanoWeb","article_publisher":"https:\/\/www.facebook.com\/redazione.cassanoweb","article_published_time":"2019-08-09T06:04:38+00:00","og_image":[{"width":960,"height":540,"url":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2019\/08\/67703553_1328946893935737_5781625643749867520_n.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"admin","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2019\/08\/09\/stasera-sul-piazzale-del-convento-qaspettando-san-lorenzoq\/#article","isPartOf":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2019\/08\/09\/stasera-sul-piazzale-del-convento-qaspettando-san-lorenzoq\/"},"author":{"name":"admin","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#\/schema\/person\/df195bc79a9b4c35127cf005f92e041b"},"headline":"Stasera sul piazzale del Convento &#8220;Aspettando san Lorenzo&#8221;","datePublished":"2019-08-09T06:04:38+00:00","mainEntityOfPage":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2019\/08\/09\/stasera-sul-piazzale-del-convento-qaspettando-san-lorenzoq\/"},"wordCount":132,"commentCount":0,"publisher":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#organization"},"image":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2019\/08\/09\/stasera-sul-piazzale-del-convento-qaspettando-san-lorenzoq\/#primaryimage"},"thumbnailUrl":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2019\/08\/67703553_1328946893935737_5781625643749867520_n.jpg","articleSection":["Appuntamenti"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2019\/08\/09\/stasera-sul-piazzale-del-convento-qaspettando-san-lorenzoq\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2019\/08\/09\/stasera-sul-piazzale-del-convento-qaspettando-san-lorenzoq\/","url":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2019\/08\/09\/stasera-sul-piazzale-del-convento-qaspettando-san-lorenzoq\/","name":"Stasera sul piazzale del Convento \"Aspettando san Lorenzo\" - Archivio CassanoWeb","isPartOf":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2019\/08\/09\/stasera-sul-piazzale-del-convento-qaspettando-san-lorenzoq\/#primaryimage"},"image":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2019\/08\/09\/stasera-sul-piazzale-del-convento-qaspettando-san-lorenzoq\/#primaryimage"},"thumbnailUrl":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2019\/08\/67703553_1328946893935737_5781625643749867520_n.jpg","datePublished":"2019-08-09T06:04:38+00:00","breadcrumb":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2019\/08\/09\/stasera-sul-piazzale-del-convento-qaspettando-san-lorenzoq\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2019\/08\/09\/stasera-sul-piazzale-del-convento-qaspettando-san-lorenzoq\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2019\/08\/09\/stasera-sul-piazzale-del-convento-qaspettando-san-lorenzoq\/#primaryimage","url":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2019\/08\/67703553_1328946893935737_5781625643749867520_n.jpg","contentUrl":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2019\/08\/67703553_1328946893935737_5781625643749867520_n.jpg","width":960,"height":540,"caption":"67703553 1328946893935737 5781625643749867520 n"},{"@type":"BreadcrumbList","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2019\/08\/09\/stasera-sul-piazzale-del-convento-qaspettando-san-lorenzoq\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/archiviocassano.lavocedelpaese.info\/"},{"@type":"ListItem","position":2,"name":"Stasera sul piazzale del Convento &#8220;Aspettando san Lorenzo&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#website","url":"https:\/\/archiviocassano.lavocedelpaese.info\/","name":"Archivio CassanoWeb","description":"La Voce del Paese - un network di idee","publisher":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/archiviocassano.lavocedelpaese.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#organization","name":"Archivio CassanoWeb","url":"https:\/\/archiviocassano.lavocedelpaese.info\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#\/schema\/logo\/image\/","url":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2024\/08\/logo-rosso-2.png","contentUrl":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2024\/08\/logo-rosso-2.png","width":491,"height":432,"caption":"Archivio CassanoWeb"},"image":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/redazione.cassanoweb"]},{"@type":"Person","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#\/schema\/person\/df195bc79a9b4c35127cf005f92e041b","name":"admin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/archiviocassano.lavocedelpaese.info"],"url":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/author\/admin_0qgz1xdp\/"}]}},"_links":{"self":[{"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/17847","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/comments?post=17847"}],"version-history":[{"count":0,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/17847\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/media\/17846"}],"wp:attachment":[{"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/media?parent=17847"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/categories?post=17847"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/tags?post=17847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}