{"id":18727,"date":"2020-09-23T16:25:18","date_gmt":"2020-09-23T16:25:18","guid":{"rendered":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2020\/09\/23\/slitta-al-5-ottobre-prossimo-lapertura-delle-scuole-a-cassano\/"},"modified":"2020-09-23T16:25:18","modified_gmt":"2020-09-23T16:25:18","slug":"slitta-al-5-ottobre-prossimo-lapertura-delle-scuole-a-cassano","status":"publish","type":"post","link":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2020\/09\/23\/slitta-al-5-ottobre-prossimo-lapertura-delle-scuole-a-cassano\/","title":{"rendered":"Slitta al 5 ottobre prossimo l&#8217;apertura delle scuole a Cassano"},"content":{"rendered":"<p><a data-flickr-embed=\"true\" href=\"https:\/\/www.flickr.com\/photos\/184752021@N05\/50375755351\/in\/dateposted-public\/\" title=\"scuole chiuse-4\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/live.staticflickr.com\/65535\/50375755351_2e265c6988_n.jpg\" width=\"320\" height=\"180\" alt=\"scuole chiuse-4\" \/><\/a><\/p>\n<p><!--more--><\/p>\n<p>Nuovo <strong>slittamento per l&#8217;apertura di tutte le scuole cassanesi al prossimo 5 ottobre.<\/strong><\/p>\n<p>E&#8217; quanto prevede una nuova Ordinanza della Sindaca di Cassano delle Murge Maria Pia Di Medio; decisione concordata con la dirigenza dei due Istituti cassanesi (il Comprensivo &#8220;Perotti-Ruffo&#8221; e il &#8220;Leonardo da Vinci&#8221;) a causa dell&#8217;emergenza sanitaria in corso per il Covid-19.<\/p>\n<p>I 13 casi conclamati come &#8220;positivi&#8221; ed i 9 in osservazione, che hanno coinvolto cittadini cassanesi, hanno&nbsp; consigliato di rimandare l&#8217;avvio del nuovo anno scolastico, inizialmente previsto, in Puglia, per il 24 settembre quindi spostato al 28 settembre ed oggi, come detto, al 5 ottobre prossimo.<\/p>\n<p>Fra l&#8217;altro ci\u00f2 consentir\u00e0 di far avanzare i lavori presso la Scuola Media nonch\u00e8 consenire l&#8217;arrivo degli arredi scolastici che al momento non sono ancora disponibili.&nbsp;<\/p>\n<p>Lo slittamento dell&#8217;inizio delle lezioni \u00e8 una decisione che anche altri Comuni, in Puglia e non solo, stanno assumendo proprio sulla base dell&#8217;andamento dei contagi.&nbsp;<\/p>\n<p>Intanto la situazione dei contagiati \u00e8 leggermente in aumento a Cassano con 17 casi conclamati e 9 in isolamento fiduciario mentre ci sono alcuni cittadini in attesa di effettuare il tampone ed altri in attesa di risposta di tamponi gi\u00e0 effettuati nei giorni scorsi.<\/p>\n<p>A tal proposito nei giorni 1-2-3 ottobre prossimi, dalla Asl Bari arriver\u00e0 a Cassano, su richiesta del Comune, una unit\u00e0 mobile con operatori specializzati che soster\u00e0 in Piazzale Tampoia (nei pressi degli Uffici ASL)&nbsp; a disposizione di chiunque voglia effettuare un tampone per verificare se si \u00e8 positivi o meno al Covid-19.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" src=\"\/\/www.slideshare.net\/slideshow\/embed_code\/key\/Aovx1GQkCEKvWg\" width=\"668\" height=\"714\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" style=\"border: 1px solid #CCC; border-width: 1px; margin-bottom: 5px; max-width: 100%;\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<div style=\"margin-bottom: 5px;\"><strong> <a href=\"\/\/www.slideshare.net\/redattori\/ordinanza-sindacale-43-2020\" title=\"Ordinanza sindacale 43 2020\" target=\"_blank\" rel=\"noopener\">Ordinanza sindacale 43 2020<\/a> <\/strong> from <strong><a href=\"https:\/\/www.slideshare.net\/redattori\" target=\"_blank\" rel=\"noopener\">redattori<\/a><\/strong><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[7],"tags":[],"class_list":["post-18727","post","type-post","status-publish","format-standard","hentry","category-attualita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Slitta al 5 ottobre prossimo l&#039;apertura delle scuole a Cassano - Archivio CassanoWeb<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2020\/09\/23\/slitta-al-5-ottobre-prossimo-lapertura-delle-scuole-a-cassano\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Slitta al 5 ottobre prossimo l&#039;apertura delle scuole a Cassano - Archivio CassanoWeb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2020\/09\/23\/slitta-al-5-ottobre-prossimo-lapertura-delle-scuole-a-cassano\/\" \/>\n<meta property=\"og:site_name\" content=\"Archivio CassanoWeb\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/redazione.cassanoweb\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-23T16:25:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/live.staticflickr.com\/65535\/50375755351_2e265c6988_n.jpg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2020\\\/09\\\/23\\\/slitta-al-5-ottobre-prossimo-lapertura-delle-scuole-a-cassano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2020\\\/09\\\/23\\\/slitta-al-5-ottobre-prossimo-lapertura-delle-scuole-a-cassano\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#\\\/schema\\\/person\\\/df195bc79a9b4c35127cf005f92e041b\"},\"headline\":\"Slitta al 5 ottobre prossimo l&#8217;apertura delle scuole a Cassano\",\"datePublished\":\"2020-09-23T16:25:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2020\\\/09\\\/23\\\/slitta-al-5-ottobre-prossimo-lapertura-delle-scuole-a-cassano\\\/\"},\"wordCount\":264,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2020\\\/09\\\/23\\\/slitta-al-5-ottobre-prossimo-lapertura-delle-scuole-a-cassano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/live.staticflickr.com\\\/65535\\\/50375755351_2e265c6988_n.jpg\",\"articleSection\":[\"Attualit\u00e0\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2020\\\/09\\\/23\\\/slitta-al-5-ottobre-prossimo-lapertura-delle-scuole-a-cassano\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2020\\\/09\\\/23\\\/slitta-al-5-ottobre-prossimo-lapertura-delle-scuole-a-cassano\\\/\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2020\\\/09\\\/23\\\/slitta-al-5-ottobre-prossimo-lapertura-delle-scuole-a-cassano\\\/\",\"name\":\"Slitta al 5 ottobre prossimo l'apertura delle scuole a Cassano - Archivio CassanoWeb\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2020\\\/09\\\/23\\\/slitta-al-5-ottobre-prossimo-lapertura-delle-scuole-a-cassano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2020\\\/09\\\/23\\\/slitta-al-5-ottobre-prossimo-lapertura-delle-scuole-a-cassano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/live.staticflickr.com\\\/65535\\\/50375755351_2e265c6988_n.jpg\",\"datePublished\":\"2020-09-23T16:25:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2020\\\/09\\\/23\\\/slitta-al-5-ottobre-prossimo-lapertura-delle-scuole-a-cassano\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2020\\\/09\\\/23\\\/slitta-al-5-ottobre-prossimo-lapertura-delle-scuole-a-cassano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2020\\\/09\\\/23\\\/slitta-al-5-ottobre-prossimo-lapertura-delle-scuole-a-cassano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/live.staticflickr.com\\\/65535\\\/50375755351_2e265c6988_n.jpg\",\"contentUrl\":\"https:\\\/\\\/live.staticflickr.com\\\/65535\\\/50375755351_2e265c6988_n.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2020\\\/09\\\/23\\\/slitta-al-5-ottobre-prossimo-lapertura-delle-scuole-a-cassano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Slitta al 5 ottobre prossimo l&#8217;apertura delle scuole a Cassano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#website\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/\",\"name\":\"Archivio CassanoWeb\",\"description\":\"La Voce del Paese - un network di idee\",\"publisher\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#organization\",\"name\":\"Archivio CassanoWeb\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/logo-rosso-2.png\",\"contentUrl\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/logo-rosso-2.png\",\"width\":491,\"height\":432,\"caption\":\"Archivio CassanoWeb\"},\"image\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/redazione.cassanoweb\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#\\\/schema\\\/person\\\/df195bc79a9b4c35127cf005f92e041b\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\"],\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/author\\\/admin_0qgz1xdp\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Slitta al 5 ottobre prossimo l'apertura delle scuole a Cassano - Archivio CassanoWeb","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2020\/09\/23\/slitta-al-5-ottobre-prossimo-lapertura-delle-scuole-a-cassano\/","og_locale":"it_IT","og_type":"article","og_title":"Slitta al 5 ottobre prossimo l'apertura delle scuole a Cassano - Archivio CassanoWeb","og_url":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2020\/09\/23\/slitta-al-5-ottobre-prossimo-lapertura-delle-scuole-a-cassano\/","og_site_name":"Archivio CassanoWeb","article_publisher":"https:\/\/www.facebook.com\/redazione.cassanoweb","article_published_time":"2020-09-23T16:25:18+00:00","og_image":[{"url":"https:\/\/live.staticflickr.com\/65535\/50375755351_2e265c6988_n.jpg","type":"","width":"","height":""}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"admin","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2020\/09\/23\/slitta-al-5-ottobre-prossimo-lapertura-delle-scuole-a-cassano\/#article","isPartOf":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2020\/09\/23\/slitta-al-5-ottobre-prossimo-lapertura-delle-scuole-a-cassano\/"},"author":{"name":"admin","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#\/schema\/person\/df195bc79a9b4c35127cf005f92e041b"},"headline":"Slitta al 5 ottobre prossimo l&#8217;apertura delle scuole a Cassano","datePublished":"2020-09-23T16:25:18+00:00","mainEntityOfPage":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2020\/09\/23\/slitta-al-5-ottobre-prossimo-lapertura-delle-scuole-a-cassano\/"},"wordCount":264,"commentCount":0,"publisher":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#organization"},"image":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2020\/09\/23\/slitta-al-5-ottobre-prossimo-lapertura-delle-scuole-a-cassano\/#primaryimage"},"thumbnailUrl":"https:\/\/live.staticflickr.com\/65535\/50375755351_2e265c6988_n.jpg","articleSection":["Attualit\u00e0"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2020\/09\/23\/slitta-al-5-ottobre-prossimo-lapertura-delle-scuole-a-cassano\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2020\/09\/23\/slitta-al-5-ottobre-prossimo-lapertura-delle-scuole-a-cassano\/","url":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2020\/09\/23\/slitta-al-5-ottobre-prossimo-lapertura-delle-scuole-a-cassano\/","name":"Slitta al 5 ottobre prossimo l'apertura delle scuole a Cassano - Archivio CassanoWeb","isPartOf":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2020\/09\/23\/slitta-al-5-ottobre-prossimo-lapertura-delle-scuole-a-cassano\/#primaryimage"},"image":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2020\/09\/23\/slitta-al-5-ottobre-prossimo-lapertura-delle-scuole-a-cassano\/#primaryimage"},"thumbnailUrl":"https:\/\/live.staticflickr.com\/65535\/50375755351_2e265c6988_n.jpg","datePublished":"2020-09-23T16:25:18+00:00","breadcrumb":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2020\/09\/23\/slitta-al-5-ottobre-prossimo-lapertura-delle-scuole-a-cassano\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2020\/09\/23\/slitta-al-5-ottobre-prossimo-lapertura-delle-scuole-a-cassano\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2020\/09\/23\/slitta-al-5-ottobre-prossimo-lapertura-delle-scuole-a-cassano\/#primaryimage","url":"https:\/\/live.staticflickr.com\/65535\/50375755351_2e265c6988_n.jpg","contentUrl":"https:\/\/live.staticflickr.com\/65535\/50375755351_2e265c6988_n.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2020\/09\/23\/slitta-al-5-ottobre-prossimo-lapertura-delle-scuole-a-cassano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/archiviocassano.lavocedelpaese.info\/"},{"@type":"ListItem","position":2,"name":"Slitta al 5 ottobre prossimo l&#8217;apertura delle scuole a Cassano"}]},{"@type":"WebSite","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#website","url":"https:\/\/archiviocassano.lavocedelpaese.info\/","name":"Archivio CassanoWeb","description":"La Voce del Paese - un network di idee","publisher":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/archiviocassano.lavocedelpaese.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#organization","name":"Archivio CassanoWeb","url":"https:\/\/archiviocassano.lavocedelpaese.info\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#\/schema\/logo\/image\/","url":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2024\/08\/logo-rosso-2.png","contentUrl":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2024\/08\/logo-rosso-2.png","width":491,"height":432,"caption":"Archivio CassanoWeb"},"image":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/redazione.cassanoweb"]},{"@type":"Person","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#\/schema\/person\/df195bc79a9b4c35127cf005f92e041b","name":"admin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/archiviocassano.lavocedelpaese.info"],"url":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/author\/admin_0qgz1xdp\/"}]}},"_links":{"self":[{"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/18727","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/comments?post=18727"}],"version-history":[{"count":0,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/18727\/revisions"}],"wp:attachment":[{"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/media?parent=18727"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/categories?post=18727"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/tags?post=18727"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}