{"id":4261,"date":"2011-08-08T16:44:56","date_gmt":"2011-08-08T16:44:56","guid":{"rendered":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2011\/08\/08\/la-gordon-confezioni-tra-ieri-a-oggi\/"},"modified":"2011-08-08T16:44:56","modified_gmt":"2011-08-08T16:44:56","slug":"la-gordon-confezioni-tra-ieri-a-oggi","status":"publish","type":"post","link":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2011\/08\/08\/la-gordon-confezioni-tra-ieri-a-oggi\/","title":{"rendered":"LA \u201cGORDON CONFEZIONI\u201d TRA IERI &#038; OGGI \u2026"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-4115\" src=\"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2011\/07\/gordon.jpg\" alt=\"gordon\" width=\"320\" height=\"150\" srcset=\"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2011\/07\/gordon.jpg 640w, https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2011\/07\/gordon-300x141.jpg 300w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/> <\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">La Gordon \u00e8 un&#8217;attivit\u00e0 sorta nei primi anni &#8217;50, per la precisione nel 1952 senza grandi ambizioni. Man mano quella piccola attivit\u00e0 cresceva e assumeva rapidamente carattere sempre pi\u00f9 da \u201cimpresa industriale\u201d grazie all&#8217;intraprendenza del \u201cprete imprenditore\u201d e dell&#8217;inarrestabile sorella Lucia. Potrebbe sembrare irriverente paragonare un prete ad un industriale, ma nel caso di Don Angelo Centrullo non \u00e8 cos\u00ec. Egli ha iniziato la sua attivit\u00e0 da \u201cindustriale\u201d con gruppi di donne impegnate nelle proprie abitazioni a confezionare modesti lavoretti e se si tiene conto del fatto che da sfondo al tutto faceva uno scenario post-bellico in cui vigeva ancora la borsa nera per potersi sfamare o le lotte tra contadini e proprietari terrieri interrotta nel periodo fascista; rincuora sapere che un Ministro di Dio davvero si sia fatto carico delle sofferenze e necessit\u00e0 dell&#8217;utenza cassanese&#8230;e cos\u00ec da piccoli ricami casalinghi sono state gettate le basi per l&#8217;attuale Gordon e molti altri maglifici del paese come Samara, King-Pull e Tip Top). All&#8217;epoca si confezionavano piccole decorazioni in panno \u201cLenxi\u201d (composizioni di fiori) utilizzate da un&#8217;industria barese per il confezionamento di prodotti. Si aggiunse la trasformazione di filati di lana in seguito per la realizzazione di maglioni, dapprima per conto di committenti che fornivano la materia prima.<\/p>\n<p>Con l&#8217;incremento dell&#8217;attivit\u00e0 entr\u00f2 in azienda il fratello minore Antonio che diede all&#8217;attivit\u00e0 una spinta definitiva per il passaggio da piccola realt\u00e0 artigianale a vera e propria impresa industriale. Il lavoro aumentava considerevolmente e la Gordon arriv\u00f2 ad impiegare ben duecento dipendenti nel solo stabilimento oltre a numerose aziende artigianali del cosiddetto indotto che occupavano altrettanti lavoratori di paesi limitrofi.<\/p>\n<p>Arriv\u00f2 cos\u00ec ad ottenere dodici agenti in Italia e tre agenti esteri partecipando a missioni economiche e fiere all&#8217;estero continuando a realizzare internamente la produzione a differenza della concorrenza che ha gi\u00e0 avviato la \u201cdelocalizzazione\u201d delle produzioni all&#8217;estero per abbassare il costo della manodopera. Dopo la sempre necessaria \u201cgavetta\u201d nei primi anni &#8217;80 il nipote di Don Angelo, Francesco Centrulli che fu nominato amministratore delegato della societ\u00e0 e tuttora la dirige e amministra apre cos\u00ec il primo ufficio di rappresentanza a Carpi nei pressi di Modena per poter essere pi\u00f9 vicino ai mercati europei che rappresentavano il sessantacinque percento delle attivit\u00e0 aziendali.<\/p>\n<p>La Gordon nacque sulla base del motto \u201cmeno guadagno, ma pi\u00f9 lavoro a tutti\u201d. Passano gli anni e pian piano cambiano anche i tempi e l&#8217;azienda si vede costretta ad acquistare nuove tecnologie per pareggiare la concorrenza sul mercato con la conseguente inevitabile riduzione del personale,venendo meno a quella morale che avrebbe voluto mantenere intatta nel tempo e che ha suscitato nei concittadini una rabbia latente e umanamente lacerante.<\/p>\n<p>Il tredici maggio 2005 giorno in cui il fondatore era stato ordinato sacerdote, Francesco Centrulli esord\u00ec con queste parole: \u201cLa Gordon non solo riesce a far fronte ai duri colpi della concorrenza e della forte crisi che attanaglia il settore, ma addirittura guarda al proprio futuro con ottimismo e con nuovi programmi di investimento, prova ne \u00e8 d&#8217;altra parte il nuovissimo stabilimento in Via Grumo\u201d. Si crea perci\u00f2 quella \u201csquadra\u201d fatta di figure professionali di alta specializzazione, produzione di alto livello qualitativo (cappotti, soprabiti, abiti in maglia,gonne e pantaloni, presenti nelle migliori boutique italiane),che ad oggi caratterizza l&#8217;azienda.<\/p>\n<p>Attualmente il lavoro della Gordon si divide in due linee di produzione, una delle quali interamente dedicata alla donne e ai propri aforismi (in aggiunta a quelle esistenti per uomo, bambino e donna tradizionali): Neera (con l&#8217;intento di dimostrare che \u201cLe parole sono cucite da un sarto ispirato, ma solo quando le indossi cominciano a vivere\u201d). Questo \u00e8 un acronimo della famosa scrittrice italiana Anna Zuccari vissuta tra gli anni &#8217;40 del 1800 e gli inizi del secolo successivo e, il cui tema dominante della narrativa \u00e8 l\u2019analisi della condizione femminile, della quale ella accetta il ruolo socialmente subordinato; limitandosi a rivendicare le ragioni del cuore e della sensibilit\u00e0 femminile a fronte della mediocrit\u00e0 della realt\u00e0 quotidiana nella quale le protagoniste dei suoi romanzi finiscono per ripiegare. Questa, assieme ad altre linee, ha una media annua di sessanta-ottanta mila capi, esportati in tutta Italia e anche all&#8217;estero. L&#8217;azienda ha poi ottenuto il riconoscimento scout come miglior azienda in grado di mantenere e far apprezzare sul mercato il rapporto qualit\u00e0-prezzo come anche la produzione propria e il made in Italy garantito. Nuove campagne pubblicitarie sosterranno la linea \u201cNEERA\u201d (evoluzione delle precedenti produzioni in linea con il bisogno delle boutique italiane ed estere) per affermare la notoriet\u00e0 dei brands di Gordon Confezioni mostrando una qualit\u00e0 sinergica del prodotto&#8221;.<\/p>\n<p>C&#8217;\u00e8 anche una fresca novit\u00e0 il \u201cCorner Concept Neera\u201d che mira alla personalizzazione del proprio spazio vendita all&#8217;interno del proprio negozio attraverso brochures,cartelli,vetrine,cataloghi&#8230;includendo assistenza sia per gli allestimenti che per la comunicazione.<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":4115,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[13],"tags":[],"class_list":["post-4261","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LA \u201cGORDON CONFEZIONI\u201d TRA IERI &amp; OGGI \u2026 - Archivio CassanoWeb<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2011\/08\/08\/la-gordon-confezioni-tra-ieri-a-oggi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LA \u201cGORDON CONFEZIONI\u201d TRA IERI &amp; OGGI \u2026 - Archivio CassanoWeb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2011\/08\/08\/la-gordon-confezioni-tra-ieri-a-oggi\/\" \/>\n<meta property=\"og:site_name\" content=\"Archivio CassanoWeb\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/redazione.cassanoweb\" \/>\n<meta property=\"article:published_time\" content=\"2011-08-08T16:44:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2011\/07\/gordon.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2011\\\/08\\\/08\\\/la-gordon-confezioni-tra-ieri-a-oggi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2011\\\/08\\\/08\\\/la-gordon-confezioni-tra-ieri-a-oggi\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#\\\/schema\\\/person\\\/df195bc79a9b4c35127cf005f92e041b\"},\"headline\":\"LA \u201cGORDON CONFEZIONI\u201d TRA IERI &#038; OGGI \u2026\",\"datePublished\":\"2011-08-08T16:44:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2011\\\/08\\\/08\\\/la-gordon-confezioni-tra-ieri-a-oggi\\\/\"},\"wordCount\":807,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2011\\\/08\\\/08\\\/la-gordon-confezioni-tra-ieri-a-oggi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2011\\\/07\\\/gordon.jpg\",\"articleSection\":[\"Economia\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2011\\\/08\\\/08\\\/la-gordon-confezioni-tra-ieri-a-oggi\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2011\\\/08\\\/08\\\/la-gordon-confezioni-tra-ieri-a-oggi\\\/\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2011\\\/08\\\/08\\\/la-gordon-confezioni-tra-ieri-a-oggi\\\/\",\"name\":\"LA \u201cGORDON CONFEZIONI\u201d TRA IERI & OGGI \u2026 - Archivio CassanoWeb\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2011\\\/08\\\/08\\\/la-gordon-confezioni-tra-ieri-a-oggi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2011\\\/08\\\/08\\\/la-gordon-confezioni-tra-ieri-a-oggi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2011\\\/07\\\/gordon.jpg\",\"datePublished\":\"2011-08-08T16:44:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2011\\\/08\\\/08\\\/la-gordon-confezioni-tra-ieri-a-oggi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2011\\\/08\\\/08\\\/la-gordon-confezioni-tra-ieri-a-oggi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2011\\\/08\\\/08\\\/la-gordon-confezioni-tra-ieri-a-oggi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2011\\\/07\\\/gordon.jpg\",\"contentUrl\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2011\\\/07\\\/gordon.jpg\",\"width\":640,\"height\":300,\"caption\":\"gordon\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2011\\\/08\\\/08\\\/la-gordon-confezioni-tra-ieri-a-oggi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LA \u201cGORDON CONFEZIONI\u201d TRA IERI &#038; OGGI \u2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#website\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/\",\"name\":\"Archivio CassanoWeb\",\"description\":\"La Voce del Paese - un network di idee\",\"publisher\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#organization\",\"name\":\"Archivio CassanoWeb\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/logo-rosso-2.png\",\"contentUrl\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/logo-rosso-2.png\",\"width\":491,\"height\":432,\"caption\":\"Archivio CassanoWeb\"},\"image\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/redazione.cassanoweb\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#\\\/schema\\\/person\\\/df195bc79a9b4c35127cf005f92e041b\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\"],\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/author\\\/admin_0qgz1xdp\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LA \u201cGORDON CONFEZIONI\u201d TRA IERI & OGGI \u2026 - Archivio CassanoWeb","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2011\/08\/08\/la-gordon-confezioni-tra-ieri-a-oggi\/","og_locale":"it_IT","og_type":"article","og_title":"LA \u201cGORDON CONFEZIONI\u201d TRA IERI & OGGI \u2026 - Archivio CassanoWeb","og_url":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2011\/08\/08\/la-gordon-confezioni-tra-ieri-a-oggi\/","og_site_name":"Archivio CassanoWeb","article_publisher":"https:\/\/www.facebook.com\/redazione.cassanoweb","article_published_time":"2011-08-08T16:44:56+00:00","og_image":[{"width":640,"height":300,"url":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2011\/07\/gordon.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"admin","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2011\/08\/08\/la-gordon-confezioni-tra-ieri-a-oggi\/#article","isPartOf":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2011\/08\/08\/la-gordon-confezioni-tra-ieri-a-oggi\/"},"author":{"name":"admin","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#\/schema\/person\/df195bc79a9b4c35127cf005f92e041b"},"headline":"LA \u201cGORDON CONFEZIONI\u201d TRA IERI &#038; OGGI \u2026","datePublished":"2011-08-08T16:44:56+00:00","mainEntityOfPage":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2011\/08\/08\/la-gordon-confezioni-tra-ieri-a-oggi\/"},"wordCount":807,"commentCount":0,"publisher":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#organization"},"image":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2011\/08\/08\/la-gordon-confezioni-tra-ieri-a-oggi\/#primaryimage"},"thumbnailUrl":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2011\/07\/gordon.jpg","articleSection":["Economia"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2011\/08\/08\/la-gordon-confezioni-tra-ieri-a-oggi\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2011\/08\/08\/la-gordon-confezioni-tra-ieri-a-oggi\/","url":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2011\/08\/08\/la-gordon-confezioni-tra-ieri-a-oggi\/","name":"LA \u201cGORDON CONFEZIONI\u201d TRA IERI & OGGI \u2026 - Archivio CassanoWeb","isPartOf":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2011\/08\/08\/la-gordon-confezioni-tra-ieri-a-oggi\/#primaryimage"},"image":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2011\/08\/08\/la-gordon-confezioni-tra-ieri-a-oggi\/#primaryimage"},"thumbnailUrl":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2011\/07\/gordon.jpg","datePublished":"2011-08-08T16:44:56+00:00","breadcrumb":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2011\/08\/08\/la-gordon-confezioni-tra-ieri-a-oggi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2011\/08\/08\/la-gordon-confezioni-tra-ieri-a-oggi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2011\/08\/08\/la-gordon-confezioni-tra-ieri-a-oggi\/#primaryimage","url":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2011\/07\/gordon.jpg","contentUrl":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2011\/07\/gordon.jpg","width":640,"height":300,"caption":"gordon"},{"@type":"BreadcrumbList","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2011\/08\/08\/la-gordon-confezioni-tra-ieri-a-oggi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/archiviocassano.lavocedelpaese.info\/"},{"@type":"ListItem","position":2,"name":"LA \u201cGORDON CONFEZIONI\u201d TRA IERI &#038; OGGI \u2026"}]},{"@type":"WebSite","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#website","url":"https:\/\/archiviocassano.lavocedelpaese.info\/","name":"Archivio CassanoWeb","description":"La Voce del Paese - un network di idee","publisher":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/archiviocassano.lavocedelpaese.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#organization","name":"Archivio CassanoWeb","url":"https:\/\/archiviocassano.lavocedelpaese.info\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#\/schema\/logo\/image\/","url":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2024\/08\/logo-rosso-2.png","contentUrl":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2024\/08\/logo-rosso-2.png","width":491,"height":432,"caption":"Archivio CassanoWeb"},"image":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/redazione.cassanoweb"]},{"@type":"Person","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#\/schema\/person\/df195bc79a9b4c35127cf005f92e041b","name":"admin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/archiviocassano.lavocedelpaese.info"],"url":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/author\/admin_0qgz1xdp\/"}]}},"_links":{"self":[{"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/4261","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/comments?post=4261"}],"version-history":[{"count":0,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/4261\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/media\/4115"}],"wp:attachment":[{"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/media?parent=4261"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/categories?post=4261"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/tags?post=4261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}