{"id":5321,"date":"2012-02-23T09:22:28","date_gmt":"2012-02-23T09:22:28","guid":{"rendered":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2012\/02\/23\/idv-cassano\/"},"modified":"2012-02-23T09:22:28","modified_gmt":"2012-02-23T09:22:28","slug":"idv-cassano","status":"publish","type":"post","link":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2012\/02\/23\/idv-cassano\/","title":{"rendered":"IdV Cassano: le balle della Di Medio sulla proroga rifiuti"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-61\" style=\"margin-right: 2px; margin-left: 2px;\" alt=\"logo-idv\" src=\"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2009\/07\/logo-idv.jpg\" width=\"320\" height=\"150\" \/><\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Siamo sempre pi\u00f9 persuasi che una <strong>certa informazione<\/strong> sia totalmente genuflessa al potere dominante e faccia addirittura da sponda agli inqualificabili minuetti di irresponsabili rappresentanti delle pubbliche istituzioni.<\/p>\n<p style=\"text-align: justify;\">Accade cos\u00ec che balle stratosferiche vengano propinate quotidianamente all\u2019opinione pubblica, con la conseguenza che il seme della mistificazione finisce sempre per avere la meglio.<\/p>\n<p style=\"text-align: justify;\">Oggi viene, tra le altre, propalata come una buona notizia quella che, invece, rappresenta oggettivamente una <strong>pessima notizia <\/strong>per la nostra comunit\u00e0 e cio\u00e8 il fatto che il servizio di nettezza urbana \u00e8 stato prorogato a favore del gestore che se lo aggiudic\u00f2 ben 8 anni fa.<\/p>\n<p style=\"text-align: justify;\">I quasi tre anni di mandato della nuova amministrazione sono un tempo sufficientemente lungo per rispettare le pi\u00f9 che note scadenze contrattuali ed evitare, dunque, il ricorso ad una proroga che il legislatore, gi\u00e0 dal 2005, ha tassativamente vietato.<\/p>\n<p style=\"text-align: justify;\">Orbene, la notizia \u00e8 che ci\u00f2 che costituisce un fallimento politico ed amministrativo della compagine di governo locale in carica, viene contrabbandato come un successo; ed il rischio, naturalmente, \u00e8 che l\u2019opinione pubblica si convinca che la realt\u00e0 sia questa, non essendo posta nella condizione di percepire l\u2019evidente manipolazione dei fatti; anzi, in una precedente intervista ad un giornale locale, che non brilla certo per obiettivit\u00e0, il Sindaco drammatizzava ad arte la vicenda per accreditarsi, oggi, il merito (che \u00e8 al contrario un <strong>palese demerito<\/strong>) di una dilatazione temporale del rapporto contrattuale con l\u2019attuale gestore del servizio.<\/p>\n<p style=\"text-align: justify;\">Sappiamo tutti, infatti, che il Consiglio Comunale fu convocato a dicembre in tutta fretta per sentirci propinare dall\u2019assessore al bilancio l\u2019assicurazione che il 17 febbraio, come era del resto doveroso, si sarebbe proceduto all\u2019aggiudicazione del nuovo appalto.<\/p>\n<p style=\"text-align: justify;\">Sta di fatto che questa \u00e8 rimasta <strong>la solita promessa da marinaio <\/strong>cui non \u00e8 seguito alcun fatto se non, appunto, la proroga, per mano del Sindaco, a favore dell\u2019attuale gestore del servizio di igiene urbana.<\/p>\n<p style=\"text-align: justify;\">Come Circolo abbiamo aperto al riguardo una riflessione che ci impegna, evidentemente, anche nel prossimo futuro, ad elaborare ogni adeguata iniziativa sul fronte politico per informare la popolazione del carico di conseguenze negative che questa scelta avr\u00e0 sull\u2019intera cittadinanza, a causa dell\u2019incapacit\u00e0 di un\u2019amministrazione di programmare, per tempo, tutte quelle iniziative atte a scongiurare il rischio di una proroga a favore di un gestore che lo stesso Sindaco, gi\u00e0 dal momento del suo insediamento, <strong>aveva bollato <\/strong>come assolutamente inadeguato ed inefficiente.<\/p>\n<p style=\"text-align: justify;\">Sta di fatto che se il Sindaco, come \u00e8 ragionevole ritenere, \u00e8 lo stesso che ha reso simili dichiarazioni, allora resta, a questo punto, del tutto incomprensibile come, al di l\u00e0 delle balle ammantate di risibili giustificazioni, nulla in concreto \u00e8 stato per tempo attuato al fine di evitare il paventato rischio della proroga di un conclamato disservizio.<\/p>\n<p style=\"text-align: justify;\">Queste cose sentivamo e sentiamo, come Circolo IDV, di dover dire, confidando che un\u2019informazione meno irreggimentata possa veicolarle per evitare il pericolo della deriva del pensiero unico.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":61,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[4],"tags":[],"class_list":["post-5321","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>IdV Cassano: le balle della Di Medio sulla proroga rifiuti - Archivio CassanoWeb<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2012\/02\/23\/idv-cassano\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IdV Cassano: le balle della Di Medio sulla proroga rifiuti - Archivio CassanoWeb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2012\/02\/23\/idv-cassano\/\" \/>\n<meta property=\"og:site_name\" content=\"Archivio CassanoWeb\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/redazione.cassanoweb\" \/>\n<meta property=\"article:published_time\" content=\"2012-02-23T09:22:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2009\/07\/logo-idv.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"410\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2012\\\/02\\\/23\\\/idv-cassano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2012\\\/02\\\/23\\\/idv-cassano\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#\\\/schema\\\/person\\\/df195bc79a9b4c35127cf005f92e041b\"},\"headline\":\"IdV Cassano: le balle della Di Medio sulla proroga rifiuti\",\"datePublished\":\"2012-02-23T09:22:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2012\\\/02\\\/23\\\/idv-cassano\\\/\"},\"wordCount\":484,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2012\\\/02\\\/23\\\/idv-cassano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2009\\\/07\\\/logo-idv.jpg\",\"articleSection\":[\"Politica\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2012\\\/02\\\/23\\\/idv-cassano\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2012\\\/02\\\/23\\\/idv-cassano\\\/\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2012\\\/02\\\/23\\\/idv-cassano\\\/\",\"name\":\"IdV Cassano: le balle della Di Medio sulla proroga rifiuti - Archivio CassanoWeb\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2012\\\/02\\\/23\\\/idv-cassano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2012\\\/02\\\/23\\\/idv-cassano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2009\\\/07\\\/logo-idv.jpg\",\"datePublished\":\"2012-02-23T09:22:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2012\\\/02\\\/23\\\/idv-cassano\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2012\\\/02\\\/23\\\/idv-cassano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2012\\\/02\\\/23\\\/idv-cassano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2009\\\/07\\\/logo-idv.jpg\",\"contentUrl\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2009\\\/07\\\/logo-idv.jpg\",\"width\":410,\"height\":200,\"caption\":\"logo-idv\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2012\\\/02\\\/23\\\/idv-cassano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"IdV Cassano: le balle della Di Medio sulla proroga rifiuti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#website\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/\",\"name\":\"Archivio CassanoWeb\",\"description\":\"La Voce del Paese - un network di idee\",\"publisher\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#organization\",\"name\":\"Archivio CassanoWeb\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/logo-rosso-2.png\",\"contentUrl\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/logo-rosso-2.png\",\"width\":491,\"height\":432,\"caption\":\"Archivio CassanoWeb\"},\"image\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/redazione.cassanoweb\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#\\\/schema\\\/person\\\/df195bc79a9b4c35127cf005f92e041b\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\"],\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/author\\\/admin_0qgz1xdp\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IdV Cassano: le balle della Di Medio sulla proroga rifiuti - Archivio CassanoWeb","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2012\/02\/23\/idv-cassano\/","og_locale":"it_IT","og_type":"article","og_title":"IdV Cassano: le balle della Di Medio sulla proroga rifiuti - Archivio CassanoWeb","og_url":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2012\/02\/23\/idv-cassano\/","og_site_name":"Archivio CassanoWeb","article_publisher":"https:\/\/www.facebook.com\/redazione.cassanoweb","article_published_time":"2012-02-23T09:22:28+00:00","og_image":[{"width":410,"height":200,"url":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2009\/07\/logo-idv.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"admin","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2012\/02\/23\/idv-cassano\/#article","isPartOf":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2012\/02\/23\/idv-cassano\/"},"author":{"name":"admin","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#\/schema\/person\/df195bc79a9b4c35127cf005f92e041b"},"headline":"IdV Cassano: le balle della Di Medio sulla proroga rifiuti","datePublished":"2012-02-23T09:22:28+00:00","mainEntityOfPage":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2012\/02\/23\/idv-cassano\/"},"wordCount":484,"commentCount":0,"publisher":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#organization"},"image":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2012\/02\/23\/idv-cassano\/#primaryimage"},"thumbnailUrl":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2009\/07\/logo-idv.jpg","articleSection":["Politica"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2012\/02\/23\/idv-cassano\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2012\/02\/23\/idv-cassano\/","url":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2012\/02\/23\/idv-cassano\/","name":"IdV Cassano: le balle della Di Medio sulla proroga rifiuti - Archivio CassanoWeb","isPartOf":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2012\/02\/23\/idv-cassano\/#primaryimage"},"image":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2012\/02\/23\/idv-cassano\/#primaryimage"},"thumbnailUrl":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2009\/07\/logo-idv.jpg","datePublished":"2012-02-23T09:22:28+00:00","breadcrumb":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2012\/02\/23\/idv-cassano\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2012\/02\/23\/idv-cassano\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2012\/02\/23\/idv-cassano\/#primaryimage","url":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2009\/07\/logo-idv.jpg","contentUrl":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2009\/07\/logo-idv.jpg","width":410,"height":200,"caption":"logo-idv"},{"@type":"BreadcrumbList","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2012\/02\/23\/idv-cassano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/archiviocassano.lavocedelpaese.info\/"},{"@type":"ListItem","position":2,"name":"IdV Cassano: le balle della Di Medio sulla proroga rifiuti"}]},{"@type":"WebSite","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#website","url":"https:\/\/archiviocassano.lavocedelpaese.info\/","name":"Archivio CassanoWeb","description":"La Voce del Paese - un network di idee","publisher":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/archiviocassano.lavocedelpaese.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#organization","name":"Archivio CassanoWeb","url":"https:\/\/archiviocassano.lavocedelpaese.info\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#\/schema\/logo\/image\/","url":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2024\/08\/logo-rosso-2.png","contentUrl":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2024\/08\/logo-rosso-2.png","width":491,"height":432,"caption":"Archivio CassanoWeb"},"image":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/redazione.cassanoweb"]},{"@type":"Person","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#\/schema\/person\/df195bc79a9b4c35127cf005f92e041b","name":"admin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/archiviocassano.lavocedelpaese.info"],"url":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/author\/admin_0qgz1xdp\/"}]}},"_links":{"self":[{"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/5321","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/comments?post=5321"}],"version-history":[{"count":0,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/5321\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/media\/61"}],"wp:attachment":[{"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/media?parent=5321"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/categories?post=5321"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/tags?post=5321"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}