{"id":5934,"date":"2012-06-19T13:55:39","date_gmt":"2012-06-19T13:55:39","guid":{"rendered":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2012\/06\/19\/pd-su-imu-irpef-e-tarsu-serve-piu-equita\/"},"modified":"2012-06-19T13:55:39","modified_gmt":"2012-06-19T13:55:39","slug":"pd-su-imu-irpef-e-tarsu-serve-piu-equita","status":"publish","type":"post","link":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2012\/06\/19\/pd-su-imu-irpef-e-tarsu-serve-piu-equita\/","title":{"rendered":"PD: su Imu, Irpef e Tarsu serve pi\u00f9 equit\u00e0"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-5933\" style=\"margin-right: 2px; margin-left: 2px;\" alt=\"logo pd\" src=\"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2012\/06\/logo_pd.jpg\" height=\"150\" width=\"320\" \/><\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: right;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\"><em>Dal Gruppo Consiliare \u201cPartito Democratico-ViviCassano\u201d, riceviamo e pubblichiamo.<\/em><\/p>\n<p style=\"text-align: justify;\">La maggioranza si era resa disponibile ad un dialogo con le minoranze per la \u201ccostruzione\u201d del bilancio di previsione del 2012 e per l\u2019introduzione della nuova IMU sulle case.<br \/>Cos\u00ec, purtroppo, non \u00e8 stato ! Alle porte del prossimo Consiglio Comunale del 26 giugno 2012,&nbsp; la maggioranza solo oggi ci mette a disposizione le proposte di delibere gi\u00e0 ben confezionate, senza alcun incontro propedeutico in fase di concertazione delle proposte.<\/p>\n<p style=\"text-align: justify;\">E qui, ad un primo sommario riscontro, scopriamo una riduzione ridicola&nbsp; (3,80 per mille invece di 4 per mille!) dell\u2019aliquota IMU sulla prima casa che ci sembra pi\u00f9 una voglia di prendere in giro i cittadini che un andare incontro alle loro difficolt\u00e0, cos\u00ec come sono una presa in giro le fantasiose ed inique&nbsp; fasce di esenzione per la addizionale comunale Irpef (che sale di ben 60%)&nbsp; e quelle che attengono la Tarsu che aumenta, ancora, del 15% come avevamo gi\u00e0 detto in precedenza. <\/p>\n<p style=\"text-align: justify;\">Ma non rinunciamo per questo alla nostra opposizione costruttiva: parteciperemo alle commissioni consiliari e chiederemo di abbassare la tassazione IMU sulle prime case al minimo consentito, per tentare di evitare che questa tassa iniqua vada a gravare su chi per anni ha lavorato e risparmiato per costruirsi un tetto. Chiederemo l\u2019applicazione di criteri equi per la graduazione dell\u2019aliquota Irpef (basandosi sul modello Isee) e per la determinazione della Tarsu\u2026<\/p>\n<p style=\"text-align: justify;\">Se ci sar\u00e0 apertura al miglioramento nell\u2019interesse dei cittadini daremo il nostro contributo nei lavori delle Commissioni Consiliari tentando di dare alternative alla maggioranza per raggiungere tale obiettivo.<\/p>\n<p style=\"text-align: justify;\">Non saremo per\u00f2 disponibili A LEGGERE SOLTANTO LE CARTE.<\/p>\n<p style=\"text-align: justify;\">La legge introdotta dal governo Monti&nbsp; offre ai Comuni il potere di manovra sulle aliquote Imu applicabili, consentendo di ridurre allo 0,2 % quella sulla prima casa e di agire anche sulle detrazioni.<\/p>\n<p style=\"text-align: justify;\">In un periodo di grave crisi come quello che stiamo attraversando, con la pressione fiscale al massimo, chiediamo che l&#8217;amministrazione comunale venga incontro alle esigenze delle famiglie cassanesi applicando le aliquote IMU al minimo, cos\u00ec come consentito dallo stesso decreto.<\/p>\n<p style=\"text-align: justify;\">E nel Consiglio comunale che sar\u00e0 convocato per il prossimo 26 giugno ci batteremo cercando l&#8217;unanimit\u00e0 di tutto il Consiglio su queste nostre proposte di interesse generale.<\/p>\n<p>&nbsp;<strong>Gruppo Consiliare PD &#8211; ViviCassano<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":5933,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[4],"tags":[],"class_list":["post-5934","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PD: su Imu, Irpef e Tarsu serve pi\u00f9 equit\u00e0 - Archivio CassanoWeb<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2012\/06\/19\/pd-su-imu-irpef-e-tarsu-serve-piu-equita\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PD: su Imu, Irpef e Tarsu serve pi\u00f9 equit\u00e0 - Archivio CassanoWeb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2012\/06\/19\/pd-su-imu-irpef-e-tarsu-serve-piu-equita\/\" \/>\n<meta property=\"og:site_name\" content=\"Archivio CassanoWeb\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/redazione.cassanoweb\" \/>\n<meta property=\"article:published_time\" content=\"2012-06-19T13:55:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2012\/06\/logo_pd.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"410\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2012\\\/06\\\/19\\\/pd-su-imu-irpef-e-tarsu-serve-piu-equita\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2012\\\/06\\\/19\\\/pd-su-imu-irpef-e-tarsu-serve-piu-equita\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#\\\/schema\\\/person\\\/df195bc79a9b4c35127cf005f92e041b\"},\"headline\":\"PD: su Imu, Irpef e Tarsu serve pi\u00f9 equit\u00e0\",\"datePublished\":\"2012-06-19T13:55:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2012\\\/06\\\/19\\\/pd-su-imu-irpef-e-tarsu-serve-piu-equita\\\/\"},\"wordCount\":384,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2012\\\/06\\\/19\\\/pd-su-imu-irpef-e-tarsu-serve-piu-equita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2012\\\/06\\\/logo_pd.jpg\",\"articleSection\":[\"Politica\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2012\\\/06\\\/19\\\/pd-su-imu-irpef-e-tarsu-serve-piu-equita\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2012\\\/06\\\/19\\\/pd-su-imu-irpef-e-tarsu-serve-piu-equita\\\/\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2012\\\/06\\\/19\\\/pd-su-imu-irpef-e-tarsu-serve-piu-equita\\\/\",\"name\":\"PD: su Imu, Irpef e Tarsu serve pi\u00f9 equit\u00e0 - Archivio CassanoWeb\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2012\\\/06\\\/19\\\/pd-su-imu-irpef-e-tarsu-serve-piu-equita\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2012\\\/06\\\/19\\\/pd-su-imu-irpef-e-tarsu-serve-piu-equita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2012\\\/06\\\/logo_pd.jpg\",\"datePublished\":\"2012-06-19T13:55:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2012\\\/06\\\/19\\\/pd-su-imu-irpef-e-tarsu-serve-piu-equita\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2012\\\/06\\\/19\\\/pd-su-imu-irpef-e-tarsu-serve-piu-equita\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2012\\\/06\\\/19\\\/pd-su-imu-irpef-e-tarsu-serve-piu-equita\\\/#primaryimage\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2012\\\/06\\\/logo_pd.jpg\",\"contentUrl\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2012\\\/06\\\/logo_pd.jpg\",\"width\":410,\"height\":200,\"caption\":\"logo pd\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2012\\\/06\\\/19\\\/pd-su-imu-irpef-e-tarsu-serve-piu-equita\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PD: su Imu, Irpef e Tarsu serve pi\u00f9 equit\u00e0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#website\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/\",\"name\":\"Archivio CassanoWeb\",\"description\":\"La Voce del Paese - un network di idee\",\"publisher\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#organization\",\"name\":\"Archivio CassanoWeb\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/logo-rosso-2.png\",\"contentUrl\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/logo-rosso-2.png\",\"width\":491,\"height\":432,\"caption\":\"Archivio CassanoWeb\"},\"image\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/redazione.cassanoweb\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#\\\/schema\\\/person\\\/df195bc79a9b4c35127cf005f92e041b\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\"],\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/author\\\/admin_0qgz1xdp\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PD: su Imu, Irpef e Tarsu serve pi\u00f9 equit\u00e0 - Archivio CassanoWeb","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2012\/06\/19\/pd-su-imu-irpef-e-tarsu-serve-piu-equita\/","og_locale":"it_IT","og_type":"article","og_title":"PD: su Imu, Irpef e Tarsu serve pi\u00f9 equit\u00e0 - Archivio CassanoWeb","og_url":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2012\/06\/19\/pd-su-imu-irpef-e-tarsu-serve-piu-equita\/","og_site_name":"Archivio CassanoWeb","article_publisher":"https:\/\/www.facebook.com\/redazione.cassanoweb","article_published_time":"2012-06-19T13:55:39+00:00","og_image":[{"width":410,"height":200,"url":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2012\/06\/logo_pd.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"admin","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2012\/06\/19\/pd-su-imu-irpef-e-tarsu-serve-piu-equita\/#article","isPartOf":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2012\/06\/19\/pd-su-imu-irpef-e-tarsu-serve-piu-equita\/"},"author":{"name":"admin","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#\/schema\/person\/df195bc79a9b4c35127cf005f92e041b"},"headline":"PD: su Imu, Irpef e Tarsu serve pi\u00f9 equit\u00e0","datePublished":"2012-06-19T13:55:39+00:00","mainEntityOfPage":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2012\/06\/19\/pd-su-imu-irpef-e-tarsu-serve-piu-equita\/"},"wordCount":384,"commentCount":0,"publisher":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#organization"},"image":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2012\/06\/19\/pd-su-imu-irpef-e-tarsu-serve-piu-equita\/#primaryimage"},"thumbnailUrl":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2012\/06\/logo_pd.jpg","articleSection":["Politica"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2012\/06\/19\/pd-su-imu-irpef-e-tarsu-serve-piu-equita\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2012\/06\/19\/pd-su-imu-irpef-e-tarsu-serve-piu-equita\/","url":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2012\/06\/19\/pd-su-imu-irpef-e-tarsu-serve-piu-equita\/","name":"PD: su Imu, Irpef e Tarsu serve pi\u00f9 equit\u00e0 - Archivio CassanoWeb","isPartOf":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2012\/06\/19\/pd-su-imu-irpef-e-tarsu-serve-piu-equita\/#primaryimage"},"image":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2012\/06\/19\/pd-su-imu-irpef-e-tarsu-serve-piu-equita\/#primaryimage"},"thumbnailUrl":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2012\/06\/logo_pd.jpg","datePublished":"2012-06-19T13:55:39+00:00","breadcrumb":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2012\/06\/19\/pd-su-imu-irpef-e-tarsu-serve-piu-equita\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2012\/06\/19\/pd-su-imu-irpef-e-tarsu-serve-piu-equita\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2012\/06\/19\/pd-su-imu-irpef-e-tarsu-serve-piu-equita\/#primaryimage","url":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2012\/06\/logo_pd.jpg","contentUrl":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2012\/06\/logo_pd.jpg","width":410,"height":200,"caption":"logo pd"},{"@type":"BreadcrumbList","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2012\/06\/19\/pd-su-imu-irpef-e-tarsu-serve-piu-equita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/archiviocassano.lavocedelpaese.info\/"},{"@type":"ListItem","position":2,"name":"PD: su Imu, Irpef e Tarsu serve pi\u00f9 equit\u00e0"}]},{"@type":"WebSite","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#website","url":"https:\/\/archiviocassano.lavocedelpaese.info\/","name":"Archivio CassanoWeb","description":"La Voce del Paese - un network di idee","publisher":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/archiviocassano.lavocedelpaese.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#organization","name":"Archivio CassanoWeb","url":"https:\/\/archiviocassano.lavocedelpaese.info\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#\/schema\/logo\/image\/","url":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2024\/08\/logo-rosso-2.png","contentUrl":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2024\/08\/logo-rosso-2.png","width":491,"height":432,"caption":"Archivio CassanoWeb"},"image":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/redazione.cassanoweb"]},{"@type":"Person","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#\/schema\/person\/df195bc79a9b4c35127cf005f92e041b","name":"admin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/archiviocassano.lavocedelpaese.info"],"url":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/author\/admin_0qgz1xdp\/"}]}},"_links":{"self":[{"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/5934","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/comments?post=5934"}],"version-history":[{"count":0,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/5934\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/media\/5933"}],"wp:attachment":[{"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/media?parent=5934"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/categories?post=5934"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/tags?post=5934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}