{"id":6966,"date":"2012-12-20T22:42:39","date_gmt":"2012-12-20T22:42:39","guid":{"rendered":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2012\/12\/20\/niente-recita-alla-scuola-dellinfanzia-una-mamma-chiede-perche\/"},"modified":"2012-12-20T22:42:39","modified_gmt":"2012-12-20T22:42:39","slug":"niente-recita-alla-scuola-dellinfanzia-una-mamma-chiede-perche","status":"publish","type":"post","link":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2012\/12\/20\/niente-recita-alla-scuola-dellinfanzia-una-mamma-chiede-perche\/","title":{"rendered":"Niente recita alla Scuola. Una mamma chiede perch\u00e8"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-6965\" style=\"margin-right: 2px; margin-left: 2px;\" alt=\"scuola dellinfanzia\" src=\"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2012\/12\/scuola_dellinfanzia.jpg\" height=\"150\" width=\"320\" srcset=\"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2012\/12\/scuola_dellinfanzia.jpg 320w, https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2012\/12\/scuola_dellinfanzia-300x141.jpg 300w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\"><i>\u201cQuest&#8217;anno presso la scuola pubblica dell&#8217;infanzia &#8220;A. Perotti&#8221; di Cassano delle Murge, a pagare il conto pi\u00f9 salato della crisi e dei tagli dei fondi della scuola, sono stati i pi\u00f9 piccoli ed innocenti: i nostri bambini\u201d. <\/i><\/p>\n<p style=\"text-align: justify;\">La lettera giunta in Redazione \u00e8 di una mamma che vuole conservare l\u2019anonimato <b>(non si capisce il motivo: quand\u2019\u00e8 che si comincer\u00e0, in questo paese, ad assumersi le proprie responsabilit\u00e0?)<\/b> e che pubblichiamo tenendo presente, tuttavia, che da informazioni raccolte dal nostro giornale presso alcune insegnanti della Scuola, la crisi c\u2019entra poco o nulla. Infatti, nel Piano dell\u2019Offerta Formativa 2012\/2013 approvato qualche giorno fa, nessuna iniziativa \u00e8 stata prevista al di fuori delle attivit\u00e0 didattiche, dunque neppure la recita natalizia.<\/p>\n<p style=\"text-align: justify;\">Una scelta \u2013 spiega una maestra \u2013 che \u00e8 stata spiegata ai rappresentanti dei genitori che l\u2019hanno condivisa cos\u00ec come tutto il corpo docente.<\/p>\n<p style=\"text-align: justify;\">Prosegue la lettera: \u201c<i>Il corpo docenti ha deciso che la manifestazione di Natale con canti e recite non verr\u00e0 effettuata. Noi genitori esprimiamo la nostra solidariet\u00e0 alle maestre che tanto si prodigano per i nostri figli, ma al tempo stesso siamo profondamente amareggiati e delusi di questa scelta. Non troviamo giusto che ai nostri bambini venga tolta una gioia ed un ricordo d&#8217;infanzia cos\u00ec prezioso, un momento di festa a cui partecipano genitori, nonni, e zii con grande entusiasmo ed attesa.<\/i><\/p>\n<p style=\"text-align: justify;\"><i>Una recita non rappresenta solo un&#8217;esperienza emotiva per i bambini, ma anche sociale ed educativa, in una fascia d&#8217;et\u00e0 in cui il gioco e lo stare insieme sono il terreno fertile per la loro crescita.<\/i><\/p>\n<p style=\"text-align: justify;\"><i>Annullare la manifesta Natalizia non ci sembra un messaggio positivo, soprattutto perch\u00e8 alla domanda &#8220;mamma, perch\u00e8 quest&#8217;anno non facciamo la recita???&#8221; non sappiamo dare una risposta chiara e condivisa. Certamente il corpo docente sar\u00e0 giunto a questa decisione dopo attente valutazioni e probabilmente in risposta ad un problema vissuto all&#8217;interno dell&#8217;istituto.<\/i><\/p>\n<p style=\"text-align: justify;\"><i>E&#8217; giusto lottare per cambiare ci\u00f2 che ci sembra sbagliato, ma \u00e8 ancora pi\u00f9 giusto scegliere il modo pi\u00f9 consono per farlo, piuttosto che privare i bambini di una esperienza positiva.<\/i><\/p>\n<p style=\"text-align: justify;\"><i>Oggi pi\u00f9 che mai bisognerebbe premiare e valorizzare il lavoro e l&#8217;impegno dei nostri piccoli figli\u201d.<\/i><\/p>\n<p style=\"text-align: justify;\">Lasciamo, come sempre, ai lettori ogni considerazione.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":6965,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[9],"tags":[],"class_list":["post-6966","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-voce-del-paese"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Niente recita alla Scuola. Una mamma chiede perch\u00e8 - Archivio CassanoWeb<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2012\/12\/20\/niente-recita-alla-scuola-dellinfanzia-una-mamma-chiede-perche\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Niente recita alla Scuola. Una mamma chiede perch\u00e8 - Archivio CassanoWeb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2012\/12\/20\/niente-recita-alla-scuola-dellinfanzia-una-mamma-chiede-perche\/\" \/>\n<meta property=\"og:site_name\" content=\"Archivio CassanoWeb\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/redazione.cassanoweb\" \/>\n<meta property=\"article:published_time\" content=\"2012-12-20T22:42:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2012\/12\/scuola_dellinfanzia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"320\" \/>\n\t<meta property=\"og:image:height\" content=\"150\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2012\\\/12\\\/20\\\/niente-recita-alla-scuola-dellinfanzia-una-mamma-chiede-perche\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2012\\\/12\\\/20\\\/niente-recita-alla-scuola-dellinfanzia-una-mamma-chiede-perche\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#\\\/schema\\\/person\\\/df195bc79a9b4c35127cf005f92e041b\"},\"headline\":\"Niente recita alla Scuola. Una mamma chiede perch\u00e8\",\"datePublished\":\"2012-12-20T22:42:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2012\\\/12\\\/20\\\/niente-recita-alla-scuola-dellinfanzia-una-mamma-chiede-perche\\\/\"},\"wordCount\":377,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2012\\\/12\\\/20\\\/niente-recita-alla-scuola-dellinfanzia-una-mamma-chiede-perche\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2012\\\/12\\\/scuola_dellinfanzia.jpg\",\"articleSection\":[\"La voce del paese\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2012\\\/12\\\/20\\\/niente-recita-alla-scuola-dellinfanzia-una-mamma-chiede-perche\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2012\\\/12\\\/20\\\/niente-recita-alla-scuola-dellinfanzia-una-mamma-chiede-perche\\\/\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2012\\\/12\\\/20\\\/niente-recita-alla-scuola-dellinfanzia-una-mamma-chiede-perche\\\/\",\"name\":\"Niente recita alla Scuola. Una mamma chiede perch\u00e8 - Archivio CassanoWeb\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2012\\\/12\\\/20\\\/niente-recita-alla-scuola-dellinfanzia-una-mamma-chiede-perche\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2012\\\/12\\\/20\\\/niente-recita-alla-scuola-dellinfanzia-una-mamma-chiede-perche\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2012\\\/12\\\/scuola_dellinfanzia.jpg\",\"datePublished\":\"2012-12-20T22:42:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2012\\\/12\\\/20\\\/niente-recita-alla-scuola-dellinfanzia-una-mamma-chiede-perche\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2012\\\/12\\\/20\\\/niente-recita-alla-scuola-dellinfanzia-una-mamma-chiede-perche\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2012\\\/12\\\/20\\\/niente-recita-alla-scuola-dellinfanzia-una-mamma-chiede-perche\\\/#primaryimage\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2012\\\/12\\\/scuola_dellinfanzia.jpg\",\"contentUrl\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2012\\\/12\\\/scuola_dellinfanzia.jpg\",\"width\":320,\"height\":150,\"caption\":\"scuola dellinfanzia\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2012\\\/12\\\/20\\\/niente-recita-alla-scuola-dellinfanzia-una-mamma-chiede-perche\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Niente recita alla Scuola. Una mamma chiede perch\u00e8\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#website\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/\",\"name\":\"Archivio CassanoWeb\",\"description\":\"La Voce del Paese - un network di idee\",\"publisher\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#organization\",\"name\":\"Archivio CassanoWeb\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/logo-rosso-2.png\",\"contentUrl\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/logo-rosso-2.png\",\"width\":491,\"height\":432,\"caption\":\"Archivio CassanoWeb\"},\"image\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/redazione.cassanoweb\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#\\\/schema\\\/person\\\/df195bc79a9b4c35127cf005f92e041b\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\"],\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/author\\\/admin_0qgz1xdp\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Niente recita alla Scuola. Una mamma chiede perch\u00e8 - Archivio CassanoWeb","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2012\/12\/20\/niente-recita-alla-scuola-dellinfanzia-una-mamma-chiede-perche\/","og_locale":"it_IT","og_type":"article","og_title":"Niente recita alla Scuola. Una mamma chiede perch\u00e8 - Archivio CassanoWeb","og_url":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2012\/12\/20\/niente-recita-alla-scuola-dellinfanzia-una-mamma-chiede-perche\/","og_site_name":"Archivio CassanoWeb","article_publisher":"https:\/\/www.facebook.com\/redazione.cassanoweb","article_published_time":"2012-12-20T22:42:39+00:00","og_image":[{"width":320,"height":150,"url":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2012\/12\/scuola_dellinfanzia.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"admin","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2012\/12\/20\/niente-recita-alla-scuola-dellinfanzia-una-mamma-chiede-perche\/#article","isPartOf":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2012\/12\/20\/niente-recita-alla-scuola-dellinfanzia-una-mamma-chiede-perche\/"},"author":{"name":"admin","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#\/schema\/person\/df195bc79a9b4c35127cf005f92e041b"},"headline":"Niente recita alla Scuola. Una mamma chiede perch\u00e8","datePublished":"2012-12-20T22:42:39+00:00","mainEntityOfPage":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2012\/12\/20\/niente-recita-alla-scuola-dellinfanzia-una-mamma-chiede-perche\/"},"wordCount":377,"commentCount":0,"publisher":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#organization"},"image":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2012\/12\/20\/niente-recita-alla-scuola-dellinfanzia-una-mamma-chiede-perche\/#primaryimage"},"thumbnailUrl":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2012\/12\/scuola_dellinfanzia.jpg","articleSection":["La voce del paese"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2012\/12\/20\/niente-recita-alla-scuola-dellinfanzia-una-mamma-chiede-perche\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2012\/12\/20\/niente-recita-alla-scuola-dellinfanzia-una-mamma-chiede-perche\/","url":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2012\/12\/20\/niente-recita-alla-scuola-dellinfanzia-una-mamma-chiede-perche\/","name":"Niente recita alla Scuola. Una mamma chiede perch\u00e8 - Archivio CassanoWeb","isPartOf":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2012\/12\/20\/niente-recita-alla-scuola-dellinfanzia-una-mamma-chiede-perche\/#primaryimage"},"image":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2012\/12\/20\/niente-recita-alla-scuola-dellinfanzia-una-mamma-chiede-perche\/#primaryimage"},"thumbnailUrl":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2012\/12\/scuola_dellinfanzia.jpg","datePublished":"2012-12-20T22:42:39+00:00","breadcrumb":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2012\/12\/20\/niente-recita-alla-scuola-dellinfanzia-una-mamma-chiede-perche\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2012\/12\/20\/niente-recita-alla-scuola-dellinfanzia-una-mamma-chiede-perche\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2012\/12\/20\/niente-recita-alla-scuola-dellinfanzia-una-mamma-chiede-perche\/#primaryimage","url":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2012\/12\/scuola_dellinfanzia.jpg","contentUrl":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2012\/12\/scuola_dellinfanzia.jpg","width":320,"height":150,"caption":"scuola dellinfanzia"},{"@type":"BreadcrumbList","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2012\/12\/20\/niente-recita-alla-scuola-dellinfanzia-una-mamma-chiede-perche\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/archiviocassano.lavocedelpaese.info\/"},{"@type":"ListItem","position":2,"name":"Niente recita alla Scuola. Una mamma chiede perch\u00e8"}]},{"@type":"WebSite","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#website","url":"https:\/\/archiviocassano.lavocedelpaese.info\/","name":"Archivio CassanoWeb","description":"La Voce del Paese - un network di idee","publisher":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/archiviocassano.lavocedelpaese.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#organization","name":"Archivio CassanoWeb","url":"https:\/\/archiviocassano.lavocedelpaese.info\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#\/schema\/logo\/image\/","url":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2024\/08\/logo-rosso-2.png","contentUrl":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2024\/08\/logo-rosso-2.png","width":491,"height":432,"caption":"Archivio CassanoWeb"},"image":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/redazione.cassanoweb"]},{"@type":"Person","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#\/schema\/person\/df195bc79a9b4c35127cf005f92e041b","name":"admin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/archiviocassano.lavocedelpaese.info"],"url":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/author\/admin_0qgz1xdp\/"}]}},"_links":{"self":[{"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/6966","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/comments?post=6966"}],"version-history":[{"count":0,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/6966\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/media\/6965"}],"wp:attachment":[{"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/media?parent=6966"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/categories?post=6966"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/tags?post=6966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}