{"id":7710,"date":"2013-06-03T21:05:16","date_gmt":"2013-06-03T21:05:16","guid":{"rendered":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2013\/06\/03\/fulmine-colpisce-cabina-enel-e-ne-povoca-incendio\/"},"modified":"2013-06-03T21:05:16","modified_gmt":"2013-06-03T21:05:16","slug":"fulmine-colpisce-cabina-enel-e-ne-povoca-incendio","status":"publish","type":"post","link":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2013\/06\/03\/fulmine-colpisce-cabina-enel-e-ne-povoca-incendio\/","title":{"rendered":"Fulmine colpisce cabina Enel e ne provoca l&#8217;incendio"},"content":{"rendered":"<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-7709\" alt=\"cabina enel bruciata\" src=\"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2013\/06\/cabina_enel_bruciata.jpg\" height=\"150\" width=\"320\" srcset=\"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2013\/06\/cabina_enel_bruciata.jpg 320w, https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2013\/06\/cabina_enel_bruciata-300x141.jpg 300w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Un fulmine di impressionante violenza ha colpito questo pomeriggio intorno alle 15.30-16.00 una cassetta di derivazione dell\u2019energia elettrica dell\u2019Enel <strong>in via De Gasperi<\/strong>, traversa di via Convento, a Cassano, provocandone l\u2019incendio.<\/p>\n<p style=\"text-align: justify;\">Sul posto i tecnici specializzati dell&#8217;azienda sono stati a lungo al lavoro per ripristinare le normali condizioni ma nel frattempo in diverse abitazioni della zona l\u2019interruzione di corrente ha provocato non pochi danni ad apparecchiature elettroniche ed elettriche.<\/p>\n<p style=\"text-align: justify;\">Spaventosa, secondo alcuni testimoni oculari, la sequenza a cui hanno assistito: il fulmine, infatti, avrebbe centrato in pieno la cabina, facendola esplodere in un incendio.<\/p>\n<p style=\"text-align: justify;\">Alcuni abitanti della zona si sono resi conto della pericolosit\u00e0 dell&#8217;incendio (che lambiva le abitazioni vicine) e sono intervenuti con molto coraggio e determinazione dato che gli incendi su strutture elettriche sono molto pericolosi ma grazie ad un estintore hanno avuto in breve ragione delle fiamme tanto che quando una squadra dei Vigili del Fuoco \u00e8 giunta sul posto, l&#8217;incendio era oramai domato.<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" style=\"margin-right: 2px; margin-left: 2px;\" alt=\"cabina enel incendiata 2\" src=\"images\/stories\/cabina_enel_incendiata_2.jpg\" height=\"397\" width=\"600\" \/><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":7709,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[8],"tags":[],"class_list":["post-7710","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronaca"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fulmine colpisce cabina Enel e ne provoca l&#039;incendio - Archivio CassanoWeb<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2013\/06\/03\/fulmine-colpisce-cabina-enel-e-ne-povoca-incendio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fulmine colpisce cabina Enel e ne provoca l&#039;incendio - Archivio CassanoWeb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2013\/06\/03\/fulmine-colpisce-cabina-enel-e-ne-povoca-incendio\/\" \/>\n<meta property=\"og:site_name\" content=\"Archivio CassanoWeb\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/redazione.cassanoweb\" \/>\n<meta property=\"article:published_time\" content=\"2013-06-03T21:05:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2013\/06\/cabina_enel_bruciata.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"320\" \/>\n\t<meta property=\"og:image:height\" content=\"150\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2013\\\/06\\\/03\\\/fulmine-colpisce-cabina-enel-e-ne-povoca-incendio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2013\\\/06\\\/03\\\/fulmine-colpisce-cabina-enel-e-ne-povoca-incendio\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#\\\/schema\\\/person\\\/df195bc79a9b4c35127cf005f92e041b\"},\"headline\":\"Fulmine colpisce cabina Enel e ne provoca l&#8217;incendio\",\"datePublished\":\"2013-06-03T21:05:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2013\\\/06\\\/03\\\/fulmine-colpisce-cabina-enel-e-ne-povoca-incendio\\\/\"},\"wordCount\":176,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2013\\\/06\\\/03\\\/fulmine-colpisce-cabina-enel-e-ne-povoca-incendio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2013\\\/06\\\/cabina_enel_bruciata.jpg\",\"articleSection\":[\"Cronaca\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2013\\\/06\\\/03\\\/fulmine-colpisce-cabina-enel-e-ne-povoca-incendio\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2013\\\/06\\\/03\\\/fulmine-colpisce-cabina-enel-e-ne-povoca-incendio\\\/\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2013\\\/06\\\/03\\\/fulmine-colpisce-cabina-enel-e-ne-povoca-incendio\\\/\",\"name\":\"Fulmine colpisce cabina Enel e ne provoca l'incendio - Archivio CassanoWeb\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2013\\\/06\\\/03\\\/fulmine-colpisce-cabina-enel-e-ne-povoca-incendio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2013\\\/06\\\/03\\\/fulmine-colpisce-cabina-enel-e-ne-povoca-incendio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2013\\\/06\\\/cabina_enel_bruciata.jpg\",\"datePublished\":\"2013-06-03T21:05:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2013\\\/06\\\/03\\\/fulmine-colpisce-cabina-enel-e-ne-povoca-incendio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2013\\\/06\\\/03\\\/fulmine-colpisce-cabina-enel-e-ne-povoca-incendio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2013\\\/06\\\/03\\\/fulmine-colpisce-cabina-enel-e-ne-povoca-incendio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2013\\\/06\\\/cabina_enel_bruciata.jpg\",\"contentUrl\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2013\\\/06\\\/cabina_enel_bruciata.jpg\",\"width\":320,\"height\":150,\"caption\":\"cabina enel bruciata\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2013\\\/06\\\/03\\\/fulmine-colpisce-cabina-enel-e-ne-povoca-incendio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fulmine colpisce cabina Enel e ne provoca l&#8217;incendio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#website\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/\",\"name\":\"Archivio CassanoWeb\",\"description\":\"La Voce del Paese - un network di idee\",\"publisher\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#organization\",\"name\":\"Archivio CassanoWeb\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/logo-rosso-2.png\",\"contentUrl\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/logo-rosso-2.png\",\"width\":491,\"height\":432,\"caption\":\"Archivio CassanoWeb\"},\"image\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/redazione.cassanoweb\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#\\\/schema\\\/person\\\/df195bc79a9b4c35127cf005f92e041b\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\"],\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/author\\\/admin_0qgz1xdp\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fulmine colpisce cabina Enel e ne provoca l'incendio - Archivio CassanoWeb","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2013\/06\/03\/fulmine-colpisce-cabina-enel-e-ne-povoca-incendio\/","og_locale":"it_IT","og_type":"article","og_title":"Fulmine colpisce cabina Enel e ne provoca l'incendio - Archivio CassanoWeb","og_url":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2013\/06\/03\/fulmine-colpisce-cabina-enel-e-ne-povoca-incendio\/","og_site_name":"Archivio CassanoWeb","article_publisher":"https:\/\/www.facebook.com\/redazione.cassanoweb","article_published_time":"2013-06-03T21:05:16+00:00","og_image":[{"width":320,"height":150,"url":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2013\/06\/cabina_enel_bruciata.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"admin","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2013\/06\/03\/fulmine-colpisce-cabina-enel-e-ne-povoca-incendio\/#article","isPartOf":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2013\/06\/03\/fulmine-colpisce-cabina-enel-e-ne-povoca-incendio\/"},"author":{"name":"admin","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#\/schema\/person\/df195bc79a9b4c35127cf005f92e041b"},"headline":"Fulmine colpisce cabina Enel e ne provoca l&#8217;incendio","datePublished":"2013-06-03T21:05:16+00:00","mainEntityOfPage":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2013\/06\/03\/fulmine-colpisce-cabina-enel-e-ne-povoca-incendio\/"},"wordCount":176,"commentCount":0,"publisher":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#organization"},"image":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2013\/06\/03\/fulmine-colpisce-cabina-enel-e-ne-povoca-incendio\/#primaryimage"},"thumbnailUrl":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2013\/06\/cabina_enel_bruciata.jpg","articleSection":["Cronaca"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2013\/06\/03\/fulmine-colpisce-cabina-enel-e-ne-povoca-incendio\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2013\/06\/03\/fulmine-colpisce-cabina-enel-e-ne-povoca-incendio\/","url":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2013\/06\/03\/fulmine-colpisce-cabina-enel-e-ne-povoca-incendio\/","name":"Fulmine colpisce cabina Enel e ne provoca l'incendio - Archivio CassanoWeb","isPartOf":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2013\/06\/03\/fulmine-colpisce-cabina-enel-e-ne-povoca-incendio\/#primaryimage"},"image":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2013\/06\/03\/fulmine-colpisce-cabina-enel-e-ne-povoca-incendio\/#primaryimage"},"thumbnailUrl":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2013\/06\/cabina_enel_bruciata.jpg","datePublished":"2013-06-03T21:05:16+00:00","breadcrumb":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2013\/06\/03\/fulmine-colpisce-cabina-enel-e-ne-povoca-incendio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2013\/06\/03\/fulmine-colpisce-cabina-enel-e-ne-povoca-incendio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2013\/06\/03\/fulmine-colpisce-cabina-enel-e-ne-povoca-incendio\/#primaryimage","url":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2013\/06\/cabina_enel_bruciata.jpg","contentUrl":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2013\/06\/cabina_enel_bruciata.jpg","width":320,"height":150,"caption":"cabina enel bruciata"},{"@type":"BreadcrumbList","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2013\/06\/03\/fulmine-colpisce-cabina-enel-e-ne-povoca-incendio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/archiviocassano.lavocedelpaese.info\/"},{"@type":"ListItem","position":2,"name":"Fulmine colpisce cabina Enel e ne provoca l&#8217;incendio"}]},{"@type":"WebSite","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#website","url":"https:\/\/archiviocassano.lavocedelpaese.info\/","name":"Archivio CassanoWeb","description":"La Voce del Paese - un network di idee","publisher":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/archiviocassano.lavocedelpaese.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#organization","name":"Archivio CassanoWeb","url":"https:\/\/archiviocassano.lavocedelpaese.info\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#\/schema\/logo\/image\/","url":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2024\/08\/logo-rosso-2.png","contentUrl":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2024\/08\/logo-rosso-2.png","width":491,"height":432,"caption":"Archivio CassanoWeb"},"image":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/redazione.cassanoweb"]},{"@type":"Person","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#\/schema\/person\/df195bc79a9b4c35127cf005f92e041b","name":"admin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/archiviocassano.lavocedelpaese.info"],"url":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/author\/admin_0qgz1xdp\/"}]}},"_links":{"self":[{"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/7710","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/comments?post=7710"}],"version-history":[{"count":0,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/7710\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/media\/7709"}],"wp:attachment":[{"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/media?parent=7710"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/categories?post=7710"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/tags?post=7710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}