{"id":8953,"date":"2014-04-07T05:35:26","date_gmt":"2014-04-07T05:35:26","guid":{"rendered":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2014\/04\/07\/prima-edizione-di-cassanoscienza-2014-ecco-il-programma\/"},"modified":"2014-04-07T05:35:26","modified_gmt":"2014-04-07T05:35:26","slug":"prima-edizione-di-cassanoscienza-2014-ecco-il-programma","status":"publish","type":"post","link":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2014\/04\/07\/prima-edizione-di-cassanoscienza-2014-ecco-il-programma\/","title":{"rendered":"Prima edizione di \u201cCassanoscienza 2014\u201d: ecco il programma"},"content":{"rendered":"<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-8952\" alt=\"cassanoscienza\" src=\"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2014\/04\/cassanoscienza.jpg\" height=\"150\" width=\"320\" \/><\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Un Festival della Scienza che parte dalla scuola per aprirsi al territorio.<\/p>\n<p style=\"text-align: justify;\">E\u2019 \u201cCassanoscienza\u201d, Festival della Scienza che si terr\u00e0 dal 7 al 13 aprile 2014 organizzato dall\u2019Istituto di Istruzione Secondaria Superiore \u201cLeonardo da Vinci\u201d e dal Comune di Cassano delle Murge. La manifestazione si svolger\u00e0 negli spazi interni ed esterni della struttura scolastica di via Padre Angelo Centrullo e nel centro storico cassanese, secondo il programma che potete leggere nella pagina a fianco.<\/p>\n<p style=\"text-align: justify;\">Il progetto \u00e8 cofinanziato dalle Parti, rappresentate rispettivamente dalla dirigente dell\u2019Istituto, Daniela Caponio, e dal &nbsp;sindaco di Cassano, Maria Pia di Medio, firmatarie dell\u2019accordo e responsabili del progetto.<\/p>\n<p style=\"text-align: justify;\">L\u2019istituto scolastico si impegna a finanziare in maniera diretta tutte le conferenze, gli spettacoli e gli incontri previsti dal programma del Festival, occupandosi anche della loro sponsorizzazione; il Comune, per sua parte, garantisce il libero accesso a strutture immobili e mobili e la fornitura di qualsiasi tipo di materiale necessario alla perfetta realizzazione dell\u2019 evento.<\/p>\n<p style=\"text-align: justify;\">Il&nbsp; Festival nasce come progetto aderente al Piano dell\u2019Offerta Formativa dell\u2019Istituto per l\u2019anno scolastico 2013\/2014, un progetto che dimentica la sua dimensione strettamente scolastica per diventare uno strumento didattico rivolto all\u2019intera cittadinanza con l\u2019intento primario di educare al pensiero critico e razionale, di educare al rispetto dell\u2019ambiente e alla valorizzazione delle risorse fisiche e umane.<\/p>\n<p style=\"text-align: justify;\">La manifestazione \u2013 che nelle precedenti edizioni era \u201cconfinata\u201d all\u2019interno della scuola, denominata \u201cSettimana della Scienza\u201d &#8211; \u00e8 un invito agli studenti ad abbandonare la percezione dell\u2019obbligo della loro formazione per capire che la conoscenza \u00e8 il primo motore per lo sviluppo dell\u2019individuo e che pu\u00f2 definirsi tale solo quando \u00e8 condivisa, per diventare incontro e scontro di idee e opinioni; il Festival \u00e8 un\u2019imperdibile occasione per gli appassionati, i curiosi e per chiunque abbia semplicemente voglia di \u201cdare un\u2019occhiata\u201d e di scambiare quattro chiacchiere su temi, problemi e prospettive del mondo contemporaneo.<\/p>\n<p style=\"text-align: justify;\">Obiettivo finale, ma non ultimo, \u00e8 la costruzione di una rete tra associazioni locali, enti formativi e singoli cittadini per creare un sistema che promuova la diffusione della cultura in ogni suo aspetto e per far s\u00ec che questo evento non sia solo l\u2019ennesimo sporadico episodio ma che sia motore trainante del risveglio di una coscienza cittadina attiva.<\/p>\n<p>Di seguito, il programma completo della manifestazione.<\/p>\n<p align=\"center\"><strong>Luned\u00ec 7 aprile<\/strong><\/p>\n<p>ore&nbsp;&nbsp; 10.00 &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Sala Consiliare Cassano delle Murge<\/p>\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; conferenza stampa<\/p>\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Intervengono:<\/p>\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Dott.ssa Maria Pia Di Medio &nbsp;&#8211; <i>Sindaco di Cassano delle Murge<\/i><\/p>\n<p><i>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <\/i>Dott.ssa Daniela Caponio &#8211; <i>D.S. Liceo Classico-Scientifico \u201cLeonardo da Vinci\u201d <br \/><\/i><\/p>\n<p><i>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <\/i>Dott. Alessio Perniola &#8211; <i>Direttore Scientifico Associazione Multiversi<\/i><\/p>\n<p>ore&nbsp;&nbsp; 16.00&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Auditorium Liceo<i> <\/i><i>\u201c<\/i>Leonardo da Vinci\u201d di Cassano delle Murge<\/p>\n<p>Saluto del Dott. Fabio Saverio Romito &#8211;&nbsp; <i>Assessore alle Politiche Comunitarie&nbsp;Politiche giovanili e Pubblica Istruzione, Politiche Comunitarie &#8211; PROVINCIA DI BARI<\/i><\/p>\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; IL TEMPO DEL GATTO E IL TEMPO DELL\u2019UOMO &#8211; incontro-dibattito sul concetto di tempo nella filosofia, nella scienza e nel cinema.<\/p>\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Intervengono:&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n<p>Prof. Felice Cimatti &#8211; <i>Docente di Filosofia del Linguaggio presso l\u2019Universit\u00e0 della Calabria<\/i>, a<i>utore del libro \u201cFilosofia dell\u2019animalit\u00e0\u201d Ed.Laterza<\/i><\/p>\n<p>Prof. Mario De Pasquale &#8211; <i>Presidente della Societ\u00e0 Filosofica Italiana di Bari<\/i> &#8211; <i>autore del libro \u201cConfilosofare in citt\u00e0\u201d Ed.Stilo<\/i><\/p>\n<p><i>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <\/i>Coordina: prof. Luciano Aprile &#8211; <i>Docente Liceo Scientifico \u201cLeonardo\u201d di Cassano delle Murge<\/i><\/p>\n<p>&nbsp;<\/p>\n<p align=\"center\"><strong>Marted\u00ec 8 aprile<\/strong><\/p>\n<p>ore 16.00&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Auditorium Liceo<i> <\/i><i>\u201c<\/i>Leonardo da Vinci\u201d di Cassano delle Murge<\/p>\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; IL TEMPO NELLA LETTERATURA &#8211; letture sceniche tra l\u2019antico e il moderno<i> a cura degli studenti del Liceo <\/i><i>\u201cLeonardo da Vinci\u201d di Cassano delle Murge<\/i><\/p>\n<p>ore 16.30&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Auditorium Liceo<i> <\/i><i>\u201c<\/i>Leonardo da Vinci\u201d di Cassano delle Murge<\/p>\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; FILOSOFISICA &#8211; incontro con l\u2019autore Alessio Perniola<\/p>\n<p>&nbsp;<\/p>\n<p align=\"center\"><strong>Mercoled\u00ec 9 aprile<\/strong><\/p>\n<p>ore 16.00&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Auditorium Liceo<i> <\/i><i>\u201c<\/i>Leonardo da Vinci\u201d di Cassano delle Murge<\/p>\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; LA BELLEZZA DISARMANTE &#8211; incontro con l\u2019autore Cesare Veronico<\/p>\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Intervengono:<\/p>\n<p>dott. Vito Giampetruzzi &#8211; <i>Assessore &#8220;Programmazione Finanziaria e Bilanci, Provveditorato, Economato e Patrimonio&#8221;<\/i><i> <\/i><i>&#8211; PROVINCIA DI BARI<\/i><\/p>\n<p>Dott.ssa Maria Pia Di Medio &nbsp;&#8211; <i>Sindaco di Cassano delle Murge<\/i><\/p>\n<p>Prof.ssa Maria Simone &#8211; Presidente <i>Club UNESCO di Cassano delle Murge<\/i><\/p>\n<p>Coordina: Dott.ssa Daniela Caponio &#8211; <i>D.S. Liceo Classico-Scientifico \u201cLeonardo da Vinci\u201d di Cassano delle Murge <\/i><\/p>\n<p><i>&nbsp;<\/i><\/p>\n<p align=\"center\"><strong>Gioved\u00ec 10 aprile<\/strong><\/p>\n<p>ore 16.00&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Auditorium Liceo<i> <\/i><i>\u201c<\/i>Leonardo da Vinci\u201d di Cassano delle Murge<\/p>\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; LA CONCEZIONE DEL TEMPO ATTRAVERSO LA TEORIA DELLA GRAVITA\u2019 QUANTISTICA<\/p>\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Prof. Giovanni Amelino Camelia &#8211; <i>Ricercatore presso il Dipartimento di Fisica dell\u2019Universit\u00e0 La Sapienza di Roma<\/i><\/p>\n<p>&nbsp;<\/p>\n<p align=\"center\"><strong>Venerd\u00ec 11 aprile<\/strong><\/p>\n<p align=\"center\"><strong>&nbsp;<\/strong><\/p>\n<p>ore 16.00&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Auditorium Liceo<i> <\/i><i>\u201c<\/i>Leonardo da Vinci\u201d di Cassano delle Murge<\/p>\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; FREGI E SPARTITI Il tempo tra matematica e musica<\/p>\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; conferenza-spettacolo <i>a cura di<\/i> Ing. Cesco Reale<\/p>\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Direzione artistica M\u00b0 Nico Sette<\/p>\n<p>ore 19.00&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Piazza Aldo Moro \u2013 Cassano delle Murge<\/p>\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; A SPASSO NEL TEMPO<\/p>\n<p>Spettacolo <i>a cura dell\u2019Associazione Multiversi con la partecipazione del gruppo RAP del Liceo \u201c<\/i><i>Leonardo da Vinci\u201d di Cassano delle Murge<\/i><\/p>\n<p align=\"center\"><strong>&nbsp;<\/strong><\/p>\n<p align=\"center\"><strong>Sabato 12 aprile<\/strong><\/p>\n<p>ore 19.00&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Centro storico di Cassano delle Murge<\/p>\n<p>LA FIERA DELLA SCIENZA animazione ludico-scientifica <i>a cura dell\u2019Associazione Multiversi, con la partecipazione degli studenti del Liceo \u201c<\/i><i>Leonardo da Vinci\u201d di Cassano delle Murge<\/i><\/p>\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; GIOCOLERIA <i>a cura dell\u2019Associazione di volontariato \u201cI Malavoglia\u201d<\/i><\/p>\n<p align=\"center\"><strong>Domenica 13 aprile<\/strong><\/p>\n<p>ore 10.00-12.00&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Centro storico di Cassano delle Murge<\/p>\n<p>LA FIERA DELLA SCIENZA animazione ludico-scientifica <i>a cura dell\u2019Associazione Multiversi con la partecipazione degli studenti del Liceo \u201c<\/i><i>Leonardo da Vinci\u201d <\/i><\/p>\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; ESIBIZIONE MUSICALE DEL CORO DEL LICEO \u201cLEONARDO DA VINCI\u201d DI CASSANO DELLE MURGE<\/p>\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <i>a cura del M\u00b0 Isabella Minafra<\/i><\/p>\n<p>&nbsp;<\/p>\n<p align=\"center\"><strong>9-10-11 aprile<\/strong><\/p>\n<p>ore 9.00-13.00&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; C.D. Perotti di Cassano delle Murge<\/p>\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; PLANETARIO &#8211; Raccontare l\u2019astronomia attraverso un viaggio virtuale tra le stelle<\/p>\n<p align=\"center\"><strong>Dal 7 al 13 aprile<\/strong><\/p>\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Liceo<i> <\/i><i>\u201c<\/i>Leonardo da Vinci\u201d di Cassano delle Murge<\/p>\n<p>&nbsp;PARADOXA percorso ludico e interattivo tra gli inganni della mente, <i>a cura dell\u2019Associazione Multiversi con la partecipazione degli studenti del Liceo \u201c<\/i><i>Leonardo da Vinci\u201d di Cassano delle Murge<\/i><\/p>\n<p>IL QUESITO E L\u2019INTUIZIONE laboratori interattivi <i>a cura degli studenti del Liceo \u201c<\/i><i>Leonardo da Vinci\u201d <\/i><\/p>\n<p>I laboratori saranno aperti la mattina dalle ore 9.00 alle ore 13.00 e il pomeriggio a partire dalle ore 15.00<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":8952,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[6],"tags":[],"class_list":["post-8953","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Prima edizione di \u201cCassanoscienza 2014\u201d: ecco il programma - Archivio CassanoWeb<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2014\/04\/07\/prima-edizione-di-cassanoscienza-2014-ecco-il-programma\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prima edizione di \u201cCassanoscienza 2014\u201d: ecco il programma - Archivio CassanoWeb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2014\/04\/07\/prima-edizione-di-cassanoscienza-2014-ecco-il-programma\/\" \/>\n<meta property=\"og:site_name\" content=\"Archivio CassanoWeb\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/redazione.cassanoweb\" \/>\n<meta property=\"article:published_time\" content=\"2014-04-07T05:35:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2014\/04\/cassanoscienza.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"731\" \/>\n\t<meta property=\"og:image:height\" content=\"304\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2014\\\/04\\\/07\\\/prima-edizione-di-cassanoscienza-2014-ecco-il-programma\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2014\\\/04\\\/07\\\/prima-edizione-di-cassanoscienza-2014-ecco-il-programma\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#\\\/schema\\\/person\\\/df195bc79a9b4c35127cf005f92e041b\"},\"headline\":\"Prima edizione di \u201cCassanoscienza 2014\u201d: ecco il programma\",\"datePublished\":\"2014-04-07T05:35:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2014\\\/04\\\/07\\\/prima-edizione-di-cassanoscienza-2014-ecco-il-programma\\\/\"},\"wordCount\":2292,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2014\\\/04\\\/07\\\/prima-edizione-di-cassanoscienza-2014-ecco-il-programma\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/cassanoscienza.jpg\",\"articleSection\":[\"Cultura\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2014\\\/04\\\/07\\\/prima-edizione-di-cassanoscienza-2014-ecco-il-programma\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2014\\\/04\\\/07\\\/prima-edizione-di-cassanoscienza-2014-ecco-il-programma\\\/\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2014\\\/04\\\/07\\\/prima-edizione-di-cassanoscienza-2014-ecco-il-programma\\\/\",\"name\":\"Prima edizione di \u201cCassanoscienza 2014\u201d: ecco il programma - Archivio CassanoWeb\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2014\\\/04\\\/07\\\/prima-edizione-di-cassanoscienza-2014-ecco-il-programma\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2014\\\/04\\\/07\\\/prima-edizione-di-cassanoscienza-2014-ecco-il-programma\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/cassanoscienza.jpg\",\"datePublished\":\"2014-04-07T05:35:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2014\\\/04\\\/07\\\/prima-edizione-di-cassanoscienza-2014-ecco-il-programma\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2014\\\/04\\\/07\\\/prima-edizione-di-cassanoscienza-2014-ecco-il-programma\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2014\\\/04\\\/07\\\/prima-edizione-di-cassanoscienza-2014-ecco-il-programma\\\/#primaryimage\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/cassanoscienza.jpg\",\"contentUrl\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/cassanoscienza.jpg\",\"width\":731,\"height\":304,\"caption\":\"cassanoscienza\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2014\\\/04\\\/07\\\/prima-edizione-di-cassanoscienza-2014-ecco-il-programma\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prima edizione di \u201cCassanoscienza 2014\u201d: ecco il programma\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#website\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/\",\"name\":\"Archivio CassanoWeb\",\"description\":\"La Voce del Paese - un network di idee\",\"publisher\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#organization\",\"name\":\"Archivio CassanoWeb\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/logo-rosso-2.png\",\"contentUrl\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/logo-rosso-2.png\",\"width\":491,\"height\":432,\"caption\":\"Archivio CassanoWeb\"},\"image\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/redazione.cassanoweb\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#\\\/schema\\\/person\\\/df195bc79a9b4c35127cf005f92e041b\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\"],\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/author\\\/admin_0qgz1xdp\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prima edizione di \u201cCassanoscienza 2014\u201d: ecco il programma - Archivio CassanoWeb","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2014\/04\/07\/prima-edizione-di-cassanoscienza-2014-ecco-il-programma\/","og_locale":"it_IT","og_type":"article","og_title":"Prima edizione di \u201cCassanoscienza 2014\u201d: ecco il programma - Archivio CassanoWeb","og_url":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2014\/04\/07\/prima-edizione-di-cassanoscienza-2014-ecco-il-programma\/","og_site_name":"Archivio CassanoWeb","article_publisher":"https:\/\/www.facebook.com\/redazione.cassanoweb","article_published_time":"2014-04-07T05:35:26+00:00","og_image":[{"width":731,"height":304,"url":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2014\/04\/cassanoscienza.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"admin","Tempo di lettura stimato":"11 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2014\/04\/07\/prima-edizione-di-cassanoscienza-2014-ecco-il-programma\/#article","isPartOf":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2014\/04\/07\/prima-edizione-di-cassanoscienza-2014-ecco-il-programma\/"},"author":{"name":"admin","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#\/schema\/person\/df195bc79a9b4c35127cf005f92e041b"},"headline":"Prima edizione di \u201cCassanoscienza 2014\u201d: ecco il programma","datePublished":"2014-04-07T05:35:26+00:00","mainEntityOfPage":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2014\/04\/07\/prima-edizione-di-cassanoscienza-2014-ecco-il-programma\/"},"wordCount":2292,"commentCount":0,"publisher":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#organization"},"image":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2014\/04\/07\/prima-edizione-di-cassanoscienza-2014-ecco-il-programma\/#primaryimage"},"thumbnailUrl":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2014\/04\/cassanoscienza.jpg","articleSection":["Cultura"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2014\/04\/07\/prima-edizione-di-cassanoscienza-2014-ecco-il-programma\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2014\/04\/07\/prima-edizione-di-cassanoscienza-2014-ecco-il-programma\/","url":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2014\/04\/07\/prima-edizione-di-cassanoscienza-2014-ecco-il-programma\/","name":"Prima edizione di \u201cCassanoscienza 2014\u201d: ecco il programma - Archivio CassanoWeb","isPartOf":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2014\/04\/07\/prima-edizione-di-cassanoscienza-2014-ecco-il-programma\/#primaryimage"},"image":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2014\/04\/07\/prima-edizione-di-cassanoscienza-2014-ecco-il-programma\/#primaryimage"},"thumbnailUrl":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2014\/04\/cassanoscienza.jpg","datePublished":"2014-04-07T05:35:26+00:00","breadcrumb":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2014\/04\/07\/prima-edizione-di-cassanoscienza-2014-ecco-il-programma\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2014\/04\/07\/prima-edizione-di-cassanoscienza-2014-ecco-il-programma\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2014\/04\/07\/prima-edizione-di-cassanoscienza-2014-ecco-il-programma\/#primaryimage","url":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2014\/04\/cassanoscienza.jpg","contentUrl":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2014\/04\/cassanoscienza.jpg","width":731,"height":304,"caption":"cassanoscienza"},{"@type":"BreadcrumbList","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2014\/04\/07\/prima-edizione-di-cassanoscienza-2014-ecco-il-programma\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/archiviocassano.lavocedelpaese.info\/"},{"@type":"ListItem","position":2,"name":"Prima edizione di \u201cCassanoscienza 2014\u201d: ecco il programma"}]},{"@type":"WebSite","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#website","url":"https:\/\/archiviocassano.lavocedelpaese.info\/","name":"Archivio CassanoWeb","description":"La Voce del Paese - un network di idee","publisher":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/archiviocassano.lavocedelpaese.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#organization","name":"Archivio CassanoWeb","url":"https:\/\/archiviocassano.lavocedelpaese.info\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#\/schema\/logo\/image\/","url":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2024\/08\/logo-rosso-2.png","contentUrl":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2024\/08\/logo-rosso-2.png","width":491,"height":432,"caption":"Archivio CassanoWeb"},"image":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/redazione.cassanoweb"]},{"@type":"Person","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#\/schema\/person\/df195bc79a9b4c35127cf005f92e041b","name":"admin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/archiviocassano.lavocedelpaese.info"],"url":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/author\/admin_0qgz1xdp\/"}]}},"_links":{"self":[{"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/8953","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/comments?post=8953"}],"version-history":[{"count":0,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/8953\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/media\/8952"}],"wp:attachment":[{"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/media?parent=8953"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/categories?post=8953"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/tags?post=8953"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}