{"id":8957,"date":"2014-04-05T05:38:03","date_gmt":"2014-04-05T05:38:03","guid":{"rendered":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2014\/04\/05\/atletico-gironata-decisiva-per-restare-in-serie-c\/"},"modified":"2014-04-05T05:38:03","modified_gmt":"2014-04-05T05:38:03","slug":"atletico-gironata-decisiva-per-restare-in-serie-c","status":"publish","type":"post","link":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2014\/04\/05\/atletico-gironata-decisiva-per-restare-in-serie-c\/","title":{"rendered":"Atletico: giornata decisiva. Il volley a Gioia"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-250\" style=\"margin-right: 2px; margin-left: 2px;\" alt=\"sport\" src=\"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2009\/09\/sport.jpg\" height=\"150\" width=\"320\" \/><\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Dopo la straordinaria prestazione di sabato scorso (3-1 contro lo Sporting Club Grotte) <strong>l\u2019Atletico Cassano<\/strong> si mantiene stretto il suo undicesimo posto e sale a quota 39 punti. Tre punti, questi, che potrebbero rivelarsi fondamentali quando oggi pomeriggio, intorno alle ore 17.00, il campionato sar\u00e0, almeno per quanto riguarda il suo svolgimento regolamentare, ufficialmente finito.<\/p>\n<p style=\"text-align: justify;\">La classifica della zona bassa, oltre alle gi\u00e0 sancite retrocessioni di Azetium Rutigliano, Pellegrino Altamura e Effe. Gi. Castellana, deve esprimere, infatti, un altro verdetto: quello riguardante le due squadre che dovranno sfidarsi ai play \u2013 out per evitare la retrocessione. Sicuro di disputare i play \u2013 out, invece, \u00e8 l\u2019Alberto C5 che, dopo la sconfitta rimediata contro il Futsal Cisternino, rimane irrimediabilmente inchiodato ai suoi 34 punti rendendo cos\u00ec impossibile l\u2019aggancio ai 38 punti del Torre Rossa Taranto.<\/p>\n<p style=\"text-align: justify;\">Si tratta, dunque, di una lotta a due tra cassanesi e tarantini che saranno rispettivamente impegnati, entrambi in trasferta, con Futsal Canosa e Ruvo, quarta e terza forza del campionato e invischiate nella lotta per accedere ai play \u2013 off.<\/p>\n<p style=\"text-align: justify;\">Occhi puntati su Canosa. dunque: alle ore 16.00 il Futsal Canosa ospita l&#8217;Atletico Cassano per una partita al cardiopalma. Ecco spiegato perch\u00e9 gli ultimi sessanta minuti di stagione si rivelano tremendamente decisivi per un gran numero di squadre.<\/p>\n<p style=\"text-align: justify;\">Si rivela abbastanza complicato anche l\u2019impegno odierno dell\u2019<strong>ASD Volley Cassano<\/strong>. Il calendario, infatti, prevede che i cassanesi facciano visita, oggi pomeriggio, alla terza forza del campionato, l\u2019A.S.D. Pallavolo Gioia. I gioiesi hanno 40 punti in classifica ma sono reduci dalla netta sconfitta per 3 \u2013 0 in casa della capolista New V. Lucera (25 \u2013 21, 28 \u2013 26, 25 \u2013 21 i parziali).<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":250,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[5],"tags":[],"class_list":["post-8957","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Atletico: giornata decisiva. Il volley a Gioia - Archivio CassanoWeb<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2014\/04\/05\/atletico-gironata-decisiva-per-restare-in-serie-c\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Atletico: giornata decisiva. Il volley a Gioia - Archivio CassanoWeb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2014\/04\/05\/atletico-gironata-decisiva-per-restare-in-serie-c\/\" \/>\n<meta property=\"og:site_name\" content=\"Archivio CassanoWeb\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/redazione.cassanoweb\" \/>\n<meta property=\"article:published_time\" content=\"2014-04-05T05:38:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2009\/09\/sport.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"410\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2014\\\/04\\\/05\\\/atletico-gironata-decisiva-per-restare-in-serie-c\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2014\\\/04\\\/05\\\/atletico-gironata-decisiva-per-restare-in-serie-c\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#\\\/schema\\\/person\\\/df195bc79a9b4c35127cf005f92e041b\"},\"headline\":\"Atletico: giornata decisiva. Il volley a Gioia\",\"datePublished\":\"2014-04-05T05:38:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2014\\\/04\\\/05\\\/atletico-gironata-decisiva-per-restare-in-serie-c\\\/\"},\"wordCount\":273,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2014\\\/04\\\/05\\\/atletico-gironata-decisiva-per-restare-in-serie-c\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2009\\\/09\\\/sport.jpg\",\"articleSection\":[\"Sport\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2014\\\/04\\\/05\\\/atletico-gironata-decisiva-per-restare-in-serie-c\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2014\\\/04\\\/05\\\/atletico-gironata-decisiva-per-restare-in-serie-c\\\/\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2014\\\/04\\\/05\\\/atletico-gironata-decisiva-per-restare-in-serie-c\\\/\",\"name\":\"Atletico: giornata decisiva. Il volley a Gioia - Archivio CassanoWeb\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2014\\\/04\\\/05\\\/atletico-gironata-decisiva-per-restare-in-serie-c\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2014\\\/04\\\/05\\\/atletico-gironata-decisiva-per-restare-in-serie-c\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2009\\\/09\\\/sport.jpg\",\"datePublished\":\"2014-04-05T05:38:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2014\\\/04\\\/05\\\/atletico-gironata-decisiva-per-restare-in-serie-c\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2014\\\/04\\\/05\\\/atletico-gironata-decisiva-per-restare-in-serie-c\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2014\\\/04\\\/05\\\/atletico-gironata-decisiva-per-restare-in-serie-c\\\/#primaryimage\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2009\\\/09\\\/sport.jpg\",\"contentUrl\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2009\\\/09\\\/sport.jpg\",\"width\":410,\"height\":200,\"caption\":\"sport\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2014\\\/04\\\/05\\\/atletico-gironata-decisiva-per-restare-in-serie-c\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Atletico: giornata decisiva. Il volley a Gioia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#website\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/\",\"name\":\"Archivio CassanoWeb\",\"description\":\"La Voce del Paese - un network di idee\",\"publisher\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#organization\",\"name\":\"Archivio CassanoWeb\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/logo-rosso-2.png\",\"contentUrl\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/logo-rosso-2.png\",\"width\":491,\"height\":432,\"caption\":\"Archivio CassanoWeb\"},\"image\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/redazione.cassanoweb\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#\\\/schema\\\/person\\\/df195bc79a9b4c35127cf005f92e041b\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\"],\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/author\\\/admin_0qgz1xdp\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Atletico: giornata decisiva. Il volley a Gioia - Archivio CassanoWeb","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2014\/04\/05\/atletico-gironata-decisiva-per-restare-in-serie-c\/","og_locale":"it_IT","og_type":"article","og_title":"Atletico: giornata decisiva. Il volley a Gioia - Archivio CassanoWeb","og_url":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2014\/04\/05\/atletico-gironata-decisiva-per-restare-in-serie-c\/","og_site_name":"Archivio CassanoWeb","article_publisher":"https:\/\/www.facebook.com\/redazione.cassanoweb","article_published_time":"2014-04-05T05:38:03+00:00","og_image":[{"width":410,"height":200,"url":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2009\/09\/sport.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"admin","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2014\/04\/05\/atletico-gironata-decisiva-per-restare-in-serie-c\/#article","isPartOf":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2014\/04\/05\/atletico-gironata-decisiva-per-restare-in-serie-c\/"},"author":{"name":"admin","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#\/schema\/person\/df195bc79a9b4c35127cf005f92e041b"},"headline":"Atletico: giornata decisiva. Il volley a Gioia","datePublished":"2014-04-05T05:38:03+00:00","mainEntityOfPage":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2014\/04\/05\/atletico-gironata-decisiva-per-restare-in-serie-c\/"},"wordCount":273,"commentCount":0,"publisher":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#organization"},"image":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2014\/04\/05\/atletico-gironata-decisiva-per-restare-in-serie-c\/#primaryimage"},"thumbnailUrl":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2009\/09\/sport.jpg","articleSection":["Sport"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2014\/04\/05\/atletico-gironata-decisiva-per-restare-in-serie-c\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2014\/04\/05\/atletico-gironata-decisiva-per-restare-in-serie-c\/","url":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2014\/04\/05\/atletico-gironata-decisiva-per-restare-in-serie-c\/","name":"Atletico: giornata decisiva. Il volley a Gioia - Archivio CassanoWeb","isPartOf":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2014\/04\/05\/atletico-gironata-decisiva-per-restare-in-serie-c\/#primaryimage"},"image":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2014\/04\/05\/atletico-gironata-decisiva-per-restare-in-serie-c\/#primaryimage"},"thumbnailUrl":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2009\/09\/sport.jpg","datePublished":"2014-04-05T05:38:03+00:00","breadcrumb":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2014\/04\/05\/atletico-gironata-decisiva-per-restare-in-serie-c\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2014\/04\/05\/atletico-gironata-decisiva-per-restare-in-serie-c\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2014\/04\/05\/atletico-gironata-decisiva-per-restare-in-serie-c\/#primaryimage","url":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2009\/09\/sport.jpg","contentUrl":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2009\/09\/sport.jpg","width":410,"height":200,"caption":"sport"},{"@type":"BreadcrumbList","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2014\/04\/05\/atletico-gironata-decisiva-per-restare-in-serie-c\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/archiviocassano.lavocedelpaese.info\/"},{"@type":"ListItem","position":2,"name":"Atletico: giornata decisiva. Il volley a Gioia"}]},{"@type":"WebSite","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#website","url":"https:\/\/archiviocassano.lavocedelpaese.info\/","name":"Archivio CassanoWeb","description":"La Voce del Paese - un network di idee","publisher":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/archiviocassano.lavocedelpaese.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#organization","name":"Archivio CassanoWeb","url":"https:\/\/archiviocassano.lavocedelpaese.info\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#\/schema\/logo\/image\/","url":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2024\/08\/logo-rosso-2.png","contentUrl":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2024\/08\/logo-rosso-2.png","width":491,"height":432,"caption":"Archivio CassanoWeb"},"image":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/redazione.cassanoweb"]},{"@type":"Person","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#\/schema\/person\/df195bc79a9b4c35127cf005f92e041b","name":"admin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/archiviocassano.lavocedelpaese.info"],"url":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/author\/admin_0qgz1xdp\/"}]}},"_links":{"self":[{"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/8957","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/comments?post=8957"}],"version-history":[{"count":0,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/8957\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/media\/250"}],"wp:attachment":[{"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/media?parent=8957"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/categories?post=8957"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/tags?post=8957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}