{"id":925,"date":"2010-02-05T07:31:43","date_gmt":"2010-02-05T07:31:43","guid":{"rendered":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2010\/02\/05\/i-pon-alla-media-v-ruffo-venerdi-la-presentazione\/"},"modified":"2010-02-05T07:31:43","modified_gmt":"2010-02-05T07:31:43","slug":"i-pon-alla-media-v-ruffo-venerdi-la-presentazione","status":"publish","type":"post","link":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2010\/02\/05\/i-pon-alla-media-v-ruffo-venerdi-la-presentazione\/","title":{"rendered":"I P.O.N. ALLA MEDIA \u201cV. RUFFO\u201d: OGGI LA PRESENTAZIONE"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-924\" alt=\"logo_scuola_media\" src=\"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2010\/02\/logo_scuola_media.jpg\" width=\"320\" height=\"156\" srcset=\"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2010\/02\/logo_scuola_media.jpg 320w, https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2010\/02\/logo_scuola_media-300x146.jpg 300w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/> <\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Saranno presentati <strong>venerd\u00ec 5 febbraio alle 17.00 <\/strong>i progetti europei della scuola Media cassanese \u201cV. Ruffo\u201d nell\u2019ambito del Programma Operativo Nazionale per l\u2019anno 2009\/2010.<\/p>\n<div style=\"text-align: justify;\"><\/div>\n<p style=\"text-align: justify;\"><em>\u201cNon PONiamoci LIMiti\u201d<\/em> lo slogan scelto dalla Dirigente scolastica \u201cMaria Rosaria Annoscia e dal gruppo di lavoro composto da Giuseppina Chiarullo (Facilitatore), Grazia Palombella (Referente per la valutazione) e Angela De Santis (Direttore Amministrativo).<\/p>\n<div style=\"text-align: justify;\"><\/div>\n<p style=\"text-align: justify;\">Due le aree individuate: una rivolta agli alunni con l\u2019obiettivo di migliorare i livelli di conoscenza e competenza dei giovani, grazie ad interventi per lo sviluppo di competenze chiave; l\u2019altro per i docenti, per accrescere la diffusione dell\u2019informazione e delle nuove tecnologie nella scuola.<\/p>\n<div style=\"text-align: justify;\"><\/div>\n<p style=\"text-align: justify;\">Complessivamente ci saranno otto progetti per i ragazzi, tutti sovvenzionati dalla Comunit\u00e0 Europea: dalla multimedialit\u00e0 al teatro, dallo sviluppo della coscienza ecologica all\u2019accrescimento delle competenze geometrico-matematiche e linguistiche, fino alla musica ed alla logica; \u00a0due quelli per i docenti, alle prese con le nuove strumentazioni e in particolare la Lavagna Interattiva Multimediale che quest\u2019anno ha fatto il suo ingresso a scuola nelle prime classi e che avr\u00e0 una rapida diffusione in tutta la scuola gi\u00e0 dal prossimo anno.<\/p>\n<div style=\"text-align: justify;\"><\/div>\n<p style=\"text-align: justify;\"><strong>Alla presentazione sono invitati soprattutto i genitori dei ragazzi della Media.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":924,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[7],"tags":[],"class_list":["post-925","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-attualita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>I P.O.N. ALLA MEDIA \u201cV. RUFFO\u201d: OGGI LA PRESENTAZIONE - Archivio CassanoWeb<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2010\/02\/05\/i-pon-alla-media-v-ruffo-venerdi-la-presentazione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"I P.O.N. ALLA MEDIA \u201cV. RUFFO\u201d: OGGI LA PRESENTAZIONE - Archivio CassanoWeb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2010\/02\/05\/i-pon-alla-media-v-ruffo-venerdi-la-presentazione\/\" \/>\n<meta property=\"og:site_name\" content=\"Archivio CassanoWeb\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/redazione.cassanoweb\" \/>\n<meta property=\"article:published_time\" content=\"2010-02-05T07:31:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2010\/02\/logo_scuola_media.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"320\" \/>\n\t<meta property=\"og:image:height\" content=\"156\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2010\\\/02\\\/05\\\/i-pon-alla-media-v-ruffo-venerdi-la-presentazione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2010\\\/02\\\/05\\\/i-pon-alla-media-v-ruffo-venerdi-la-presentazione\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#\\\/schema\\\/person\\\/df195bc79a9b4c35127cf005f92e041b\"},\"headline\":\"I P.O.N. ALLA MEDIA \u201cV. RUFFO\u201d: OGGI LA PRESENTAZIONE\",\"datePublished\":\"2010-02-05T07:31:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2010\\\/02\\\/05\\\/i-pon-alla-media-v-ruffo-venerdi-la-presentazione\\\/\"},\"wordCount\":206,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2010\\\/02\\\/05\\\/i-pon-alla-media-v-ruffo-venerdi-la-presentazione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2010\\\/02\\\/logo_scuola_media.jpg\",\"articleSection\":[\"Attualit\u00e0\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2010\\\/02\\\/05\\\/i-pon-alla-media-v-ruffo-venerdi-la-presentazione\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2010\\\/02\\\/05\\\/i-pon-alla-media-v-ruffo-venerdi-la-presentazione\\\/\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2010\\\/02\\\/05\\\/i-pon-alla-media-v-ruffo-venerdi-la-presentazione\\\/\",\"name\":\"I P.O.N. ALLA MEDIA \u201cV. RUFFO\u201d: OGGI LA PRESENTAZIONE - Archivio CassanoWeb\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2010\\\/02\\\/05\\\/i-pon-alla-media-v-ruffo-venerdi-la-presentazione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2010\\\/02\\\/05\\\/i-pon-alla-media-v-ruffo-venerdi-la-presentazione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2010\\\/02\\\/logo_scuola_media.jpg\",\"datePublished\":\"2010-02-05T07:31:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2010\\\/02\\\/05\\\/i-pon-alla-media-v-ruffo-venerdi-la-presentazione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2010\\\/02\\\/05\\\/i-pon-alla-media-v-ruffo-venerdi-la-presentazione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2010\\\/02\\\/05\\\/i-pon-alla-media-v-ruffo-venerdi-la-presentazione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2010\\\/02\\\/logo_scuola_media.jpg\",\"contentUrl\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2010\\\/02\\\/logo_scuola_media.jpg\",\"width\":320,\"height\":156,\"caption\":\"logo_scuola_media\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2010\\\/02\\\/05\\\/i-pon-alla-media-v-ruffo-venerdi-la-presentazione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"I P.O.N. ALLA MEDIA \u201cV. RUFFO\u201d: OGGI LA PRESENTAZIONE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#website\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/\",\"name\":\"Archivio CassanoWeb\",\"description\":\"La Voce del Paese - un network di idee\",\"publisher\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#organization\",\"name\":\"Archivio CassanoWeb\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/logo-rosso-2.png\",\"contentUrl\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/logo-rosso-2.png\",\"width\":491,\"height\":432,\"caption\":\"Archivio CassanoWeb\"},\"image\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/redazione.cassanoweb\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#\\\/schema\\\/person\\\/df195bc79a9b4c35127cf005f92e041b\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\"],\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/author\\\/admin_0qgz1xdp\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"I P.O.N. ALLA MEDIA \u201cV. RUFFO\u201d: OGGI LA PRESENTAZIONE - Archivio CassanoWeb","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2010\/02\/05\/i-pon-alla-media-v-ruffo-venerdi-la-presentazione\/","og_locale":"it_IT","og_type":"article","og_title":"I P.O.N. ALLA MEDIA \u201cV. RUFFO\u201d: OGGI LA PRESENTAZIONE - Archivio CassanoWeb","og_url":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2010\/02\/05\/i-pon-alla-media-v-ruffo-venerdi-la-presentazione\/","og_site_name":"Archivio CassanoWeb","article_publisher":"https:\/\/www.facebook.com\/redazione.cassanoweb","article_published_time":"2010-02-05T07:31:43+00:00","og_image":[{"width":320,"height":156,"url":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2010\/02\/logo_scuola_media.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"admin","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2010\/02\/05\/i-pon-alla-media-v-ruffo-venerdi-la-presentazione\/#article","isPartOf":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2010\/02\/05\/i-pon-alla-media-v-ruffo-venerdi-la-presentazione\/"},"author":{"name":"admin","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#\/schema\/person\/df195bc79a9b4c35127cf005f92e041b"},"headline":"I P.O.N. ALLA MEDIA \u201cV. RUFFO\u201d: OGGI LA PRESENTAZIONE","datePublished":"2010-02-05T07:31:43+00:00","mainEntityOfPage":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2010\/02\/05\/i-pon-alla-media-v-ruffo-venerdi-la-presentazione\/"},"wordCount":206,"commentCount":0,"publisher":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#organization"},"image":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2010\/02\/05\/i-pon-alla-media-v-ruffo-venerdi-la-presentazione\/#primaryimage"},"thumbnailUrl":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2010\/02\/logo_scuola_media.jpg","articleSection":["Attualit\u00e0"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2010\/02\/05\/i-pon-alla-media-v-ruffo-venerdi-la-presentazione\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2010\/02\/05\/i-pon-alla-media-v-ruffo-venerdi-la-presentazione\/","url":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2010\/02\/05\/i-pon-alla-media-v-ruffo-venerdi-la-presentazione\/","name":"I P.O.N. ALLA MEDIA \u201cV. RUFFO\u201d: OGGI LA PRESENTAZIONE - Archivio CassanoWeb","isPartOf":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2010\/02\/05\/i-pon-alla-media-v-ruffo-venerdi-la-presentazione\/#primaryimage"},"image":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2010\/02\/05\/i-pon-alla-media-v-ruffo-venerdi-la-presentazione\/#primaryimage"},"thumbnailUrl":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2010\/02\/logo_scuola_media.jpg","datePublished":"2010-02-05T07:31:43+00:00","breadcrumb":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2010\/02\/05\/i-pon-alla-media-v-ruffo-venerdi-la-presentazione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2010\/02\/05\/i-pon-alla-media-v-ruffo-venerdi-la-presentazione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2010\/02\/05\/i-pon-alla-media-v-ruffo-venerdi-la-presentazione\/#primaryimage","url":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2010\/02\/logo_scuola_media.jpg","contentUrl":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2010\/02\/logo_scuola_media.jpg","width":320,"height":156,"caption":"logo_scuola_media"},{"@type":"BreadcrumbList","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2010\/02\/05\/i-pon-alla-media-v-ruffo-venerdi-la-presentazione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/archiviocassano.lavocedelpaese.info\/"},{"@type":"ListItem","position":2,"name":"I P.O.N. ALLA MEDIA \u201cV. RUFFO\u201d: OGGI LA PRESENTAZIONE"}]},{"@type":"WebSite","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#website","url":"https:\/\/archiviocassano.lavocedelpaese.info\/","name":"Archivio CassanoWeb","description":"La Voce del Paese - un network di idee","publisher":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/archiviocassano.lavocedelpaese.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#organization","name":"Archivio CassanoWeb","url":"https:\/\/archiviocassano.lavocedelpaese.info\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#\/schema\/logo\/image\/","url":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2024\/08\/logo-rosso-2.png","contentUrl":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2024\/08\/logo-rosso-2.png","width":491,"height":432,"caption":"Archivio CassanoWeb"},"image":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/redazione.cassanoweb"]},{"@type":"Person","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#\/schema\/person\/df195bc79a9b4c35127cf005f92e041b","name":"admin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/archiviocassano.lavocedelpaese.info"],"url":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/author\/admin_0qgz1xdp\/"}]}},"_links":{"self":[{"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/925","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/comments?post=925"}],"version-history":[{"count":0,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/925\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/media\/924"}],"wp:attachment":[{"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/media?parent=925"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/categories?post=925"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/tags?post=925"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}