{"id":944,"date":"2010-02-06T08:43:34","date_gmt":"2010-02-06T08:43:34","guid":{"rendered":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2010\/02\/06\/vivere-e-ri-vivere-nella-pittura-personale-di-rossella-laterza\/"},"modified":"2010-02-06T08:43:34","modified_gmt":"2010-02-06T08:43:34","slug":"vivere-e-ri-vivere-nella-pittura-personale-di-rossella-laterza","status":"publish","type":"post","link":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2010\/02\/06\/vivere-e-ri-vivere-nella-pittura-personale-di-rossella-laterza\/","title":{"rendered":"\u201cVIVERE E RI-VIVERE NELLA PITTURA\u201d, MOSTRA DI LATERZA"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-942\" alt=\"Biblioteca_comunale\" src=\"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2010\/02\/Biblioteca_comunale.jpg\" width=\"320\" height=\"156\" srcset=\"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2010\/02\/Biblioteca_comunale.jpg 320w, https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2010\/02\/Biblioteca_comunale-300x146.jpg 300w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/> <\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Si inaugura quest\u2019oggi, 6 febbraio 2010, presso la sala conferenze della Biblioteca Comunale \u201cA. Perotti\u201d di Cassano, la personale dell&#8217;artista Rossella Laterza intitolata \u201cVivere e Ri-Vivere nella pittura\u201d, curata da \u201clobiettivonline\u201d , \u201cPensiero e Arte\u201d e \u201cMessaggi edizioni\u201d con il patrocinio del Comune.<\/p>\n<div style=\"text-align: justify;\"><\/div>\n<p style=\"text-align: justify;\"><strong>La mostra rester\u00e0 aperta sino al 12 febbraio 2010, e sar\u00e0 visitabile tutti i giorni dalle ore 18.00 alle ore 20.00.<\/strong><\/p>\n<div style=\"text-align: justify;\"><\/div>\n<p style=\"text-align: justify;\">Interverrano al vernissage l&#8217;Assessore alla cultura Pierpaola Sapienza, il critico d\u2019arte Lello Spinelli, la giornalista Maria Vinella, l&#8217;editore Nicola Surico.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-943\" alt=\"mostra_rossella_laterza\" src=\"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2010\/02\/mostra_rossella_laterza.jpg\" width=\"400\" height=\"585\" srcset=\"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2010\/02\/mostra_rossella_laterza.jpg 400w, https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2010\/02\/mostra_rossella_laterza-205x300.jpg 205w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":942,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[6],"tags":[],"class_list":["post-944","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u201cVIVERE E RI-VIVERE NELLA PITTURA\u201d, MOSTRA DI LATERZA - Archivio CassanoWeb<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2010\/02\/06\/vivere-e-ri-vivere-nella-pittura-personale-di-rossella-laterza\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201cVIVERE E RI-VIVERE NELLA PITTURA\u201d, MOSTRA DI LATERZA - Archivio CassanoWeb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2010\/02\/06\/vivere-e-ri-vivere-nella-pittura-personale-di-rossella-laterza\/\" \/>\n<meta property=\"og:site_name\" content=\"Archivio CassanoWeb\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/redazione.cassanoweb\" \/>\n<meta property=\"article:published_time\" content=\"2010-02-06T08:43:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2010\/02\/Biblioteca_comunale.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"320\" \/>\n\t<meta property=\"og:image:height\" content=\"156\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2010\\\/02\\\/06\\\/vivere-e-ri-vivere-nella-pittura-personale-di-rossella-laterza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2010\\\/02\\\/06\\\/vivere-e-ri-vivere-nella-pittura-personale-di-rossella-laterza\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#\\\/schema\\\/person\\\/df195bc79a9b4c35127cf005f92e041b\"},\"headline\":\"\u201cVIVERE E RI-VIVERE NELLA PITTURA\u201d, MOSTRA DI LATERZA\",\"datePublished\":\"2010-02-06T08:43:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2010\\\/02\\\/06\\\/vivere-e-ri-vivere-nella-pittura-personale-di-rossella-laterza\\\/\"},\"wordCount\":90,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2010\\\/02\\\/06\\\/vivere-e-ri-vivere-nella-pittura-personale-di-rossella-laterza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2010\\\/02\\\/Biblioteca_comunale.jpg\",\"articleSection\":[\"Cultura\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2010\\\/02\\\/06\\\/vivere-e-ri-vivere-nella-pittura-personale-di-rossella-laterza\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2010\\\/02\\\/06\\\/vivere-e-ri-vivere-nella-pittura-personale-di-rossella-laterza\\\/\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2010\\\/02\\\/06\\\/vivere-e-ri-vivere-nella-pittura-personale-di-rossella-laterza\\\/\",\"name\":\"\u201cVIVERE E RI-VIVERE NELLA PITTURA\u201d, MOSTRA DI LATERZA - Archivio CassanoWeb\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2010\\\/02\\\/06\\\/vivere-e-ri-vivere-nella-pittura-personale-di-rossella-laterza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2010\\\/02\\\/06\\\/vivere-e-ri-vivere-nella-pittura-personale-di-rossella-laterza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2010\\\/02\\\/Biblioteca_comunale.jpg\",\"datePublished\":\"2010-02-06T08:43:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2010\\\/02\\\/06\\\/vivere-e-ri-vivere-nella-pittura-personale-di-rossella-laterza\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2010\\\/02\\\/06\\\/vivere-e-ri-vivere-nella-pittura-personale-di-rossella-laterza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2010\\\/02\\\/06\\\/vivere-e-ri-vivere-nella-pittura-personale-di-rossella-laterza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2010\\\/02\\\/Biblioteca_comunale.jpg\",\"contentUrl\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2010\\\/02\\\/Biblioteca_comunale.jpg\",\"width\":320,\"height\":156,\"caption\":\"Biblioteca_comunale\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2010\\\/02\\\/06\\\/vivere-e-ri-vivere-nella-pittura-personale-di-rossella-laterza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201cVIVERE E RI-VIVERE NELLA PITTURA\u201d, MOSTRA DI LATERZA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#website\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/\",\"name\":\"Archivio CassanoWeb\",\"description\":\"La Voce del Paese - un network di idee\",\"publisher\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#organization\",\"name\":\"Archivio CassanoWeb\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/logo-rosso-2.png\",\"contentUrl\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/logo-rosso-2.png\",\"width\":491,\"height\":432,\"caption\":\"Archivio CassanoWeb\"},\"image\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/redazione.cassanoweb\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#\\\/schema\\\/person\\\/df195bc79a9b4c35127cf005f92e041b\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\"],\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/author\\\/admin_0qgz1xdp\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201cVIVERE E RI-VIVERE NELLA PITTURA\u201d, MOSTRA DI LATERZA - Archivio CassanoWeb","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2010\/02\/06\/vivere-e-ri-vivere-nella-pittura-personale-di-rossella-laterza\/","og_locale":"it_IT","og_type":"article","og_title":"\u201cVIVERE E RI-VIVERE NELLA PITTURA\u201d, MOSTRA DI LATERZA - Archivio CassanoWeb","og_url":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2010\/02\/06\/vivere-e-ri-vivere-nella-pittura-personale-di-rossella-laterza\/","og_site_name":"Archivio CassanoWeb","article_publisher":"https:\/\/www.facebook.com\/redazione.cassanoweb","article_published_time":"2010-02-06T08:43:34+00:00","og_image":[{"width":320,"height":156,"url":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2010\/02\/Biblioteca_comunale.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"admin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2010\/02\/06\/vivere-e-ri-vivere-nella-pittura-personale-di-rossella-laterza\/#article","isPartOf":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2010\/02\/06\/vivere-e-ri-vivere-nella-pittura-personale-di-rossella-laterza\/"},"author":{"name":"admin","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#\/schema\/person\/df195bc79a9b4c35127cf005f92e041b"},"headline":"\u201cVIVERE E RI-VIVERE NELLA PITTURA\u201d, MOSTRA DI LATERZA","datePublished":"2010-02-06T08:43:34+00:00","mainEntityOfPage":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2010\/02\/06\/vivere-e-ri-vivere-nella-pittura-personale-di-rossella-laterza\/"},"wordCount":90,"commentCount":0,"publisher":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#organization"},"image":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2010\/02\/06\/vivere-e-ri-vivere-nella-pittura-personale-di-rossella-laterza\/#primaryimage"},"thumbnailUrl":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2010\/02\/Biblioteca_comunale.jpg","articleSection":["Cultura"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2010\/02\/06\/vivere-e-ri-vivere-nella-pittura-personale-di-rossella-laterza\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2010\/02\/06\/vivere-e-ri-vivere-nella-pittura-personale-di-rossella-laterza\/","url":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2010\/02\/06\/vivere-e-ri-vivere-nella-pittura-personale-di-rossella-laterza\/","name":"\u201cVIVERE E RI-VIVERE NELLA PITTURA\u201d, MOSTRA DI LATERZA - Archivio CassanoWeb","isPartOf":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2010\/02\/06\/vivere-e-ri-vivere-nella-pittura-personale-di-rossella-laterza\/#primaryimage"},"image":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2010\/02\/06\/vivere-e-ri-vivere-nella-pittura-personale-di-rossella-laterza\/#primaryimage"},"thumbnailUrl":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2010\/02\/Biblioteca_comunale.jpg","datePublished":"2010-02-06T08:43:34+00:00","breadcrumb":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2010\/02\/06\/vivere-e-ri-vivere-nella-pittura-personale-di-rossella-laterza\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2010\/02\/06\/vivere-e-ri-vivere-nella-pittura-personale-di-rossella-laterza\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2010\/02\/06\/vivere-e-ri-vivere-nella-pittura-personale-di-rossella-laterza\/#primaryimage","url":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2010\/02\/Biblioteca_comunale.jpg","contentUrl":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2010\/02\/Biblioteca_comunale.jpg","width":320,"height":156,"caption":"Biblioteca_comunale"},{"@type":"BreadcrumbList","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2010\/02\/06\/vivere-e-ri-vivere-nella-pittura-personale-di-rossella-laterza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/archiviocassano.lavocedelpaese.info\/"},{"@type":"ListItem","position":2,"name":"\u201cVIVERE E RI-VIVERE NELLA PITTURA\u201d, MOSTRA DI LATERZA"}]},{"@type":"WebSite","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#website","url":"https:\/\/archiviocassano.lavocedelpaese.info\/","name":"Archivio CassanoWeb","description":"La Voce del Paese - un network di idee","publisher":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/archiviocassano.lavocedelpaese.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#organization","name":"Archivio CassanoWeb","url":"https:\/\/archiviocassano.lavocedelpaese.info\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#\/schema\/logo\/image\/","url":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2024\/08\/logo-rosso-2.png","contentUrl":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2024\/08\/logo-rosso-2.png","width":491,"height":432,"caption":"Archivio CassanoWeb"},"image":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/redazione.cassanoweb"]},{"@type":"Person","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#\/schema\/person\/df195bc79a9b4c35127cf005f92e041b","name":"admin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/archiviocassano.lavocedelpaese.info"],"url":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/author\/admin_0qgz1xdp\/"}]}},"_links":{"self":[{"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/944","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/comments?post=944"}],"version-history":[{"count":0,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/944\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/media\/942"}],"wp:attachment":[{"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/media?parent=944"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/categories?post=944"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/tags?post=944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}