{"id":9686,"date":"2014-09-06T21:54:45","date_gmt":"2014-09-06T21:54:45","guid":{"rendered":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2014\/09\/06\/la-storia-di-domenico-modugno-venerdi-ai-giardini-del-portico\/"},"modified":"2014-09-06T21:54:45","modified_gmt":"2014-09-06T21:54:45","slug":"la-storia-di-domenico-modugno-venerdi-ai-giardini-del-portico","status":"publish","type":"post","link":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2014\/09\/06\/la-storia-di-domenico-modugno-venerdi-ai-giardini-del-portico\/","title":{"rendered":"La storia di Domenico Modugno venerd\u00ec ai Giardini del Portico"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-9685\" src=\"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2014\/09\/questo_sono_io.jpg\" alt=\"questo sono io\" style=\"margin-right: 2px; margin-left: 2px;\" width=\"320\" height=\"150\" srcset=\"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2014\/09\/questo_sono_io.jpg 320w, https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2014\/09\/questo_sono_io-300x141.jpg 300w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\"><em>&nbsp;&#8220;Questo sono io: la storia di Domenico Modugno&#8221;<\/em> il titolo del nuovo recital musicale prodotto da Tony Petruzzellis che andr\u00e0 in scena&nbsp;<strong>venerd\u00ec 12 settembre alle ore 21.00&nbsp;<\/strong>presso&nbsp;<strong>I Giardini del Portico Ricevimenti&#8221;.<\/strong><\/p>\n<p style=\"text-align: justify;\">Una serata che racconter\u00e0 la storia del grande cantante polignanese attraverso una lunga carrellata dei suoi successi, delle sue canzoni, dei suoi amori, del suo affetto per la sua Puglia, abbandonata da ragazzo e poi sempre ricercata.<\/p>\n<p style=\"text-align: justify;\">Il cast artistico \u00e8 composto da&nbsp;<strong>Paolo Magno&nbsp;<\/strong>alla chitarra,&nbsp;<strong>Domenico Lillo<\/strong> alla batteria e percussioni,&nbsp;<strong>Alessio Giove&nbsp;<\/strong>alla fisarmonica con la partecipazione di <strong>Domenico Terrone<\/strong>&nbsp;e&nbsp;<strong>Tony Petruzzellis&nbsp;<\/strong>come voce narrante e canto.<\/p>\n<p style=\"text-align: justify;\">Il costo del biglietto \u00e8 di 7,00 euro compresa la deguastazione di prodotti tipici pugliesi.<\/p>\n<p style=\"text-align: justify;\">Info e prenotazioni: 348.443.5078.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":9685,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[11],"tags":[],"class_list":["post-9686","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-appuntamenti"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La storia di Domenico Modugno venerd\u00ec ai Giardini del Portico - Archivio CassanoWeb<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2014\/09\/06\/la-storia-di-domenico-modugno-venerdi-ai-giardini-del-portico\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La storia di Domenico Modugno venerd\u00ec ai Giardini del Portico - Archivio CassanoWeb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2014\/09\/06\/la-storia-di-domenico-modugno-venerdi-ai-giardini-del-portico\/\" \/>\n<meta property=\"og:site_name\" content=\"Archivio CassanoWeb\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/redazione.cassanoweb\" \/>\n<meta property=\"article:published_time\" content=\"2014-09-06T21:54:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2014\/09\/questo_sono_io.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"320\" \/>\n\t<meta property=\"og:image:height\" content=\"150\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2014\\\/09\\\/06\\\/la-storia-di-domenico-modugno-venerdi-ai-giardini-del-portico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2014\\\/09\\\/06\\\/la-storia-di-domenico-modugno-venerdi-ai-giardini-del-portico\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#\\\/schema\\\/person\\\/df195bc79a9b4c35127cf005f92e041b\"},\"headline\":\"La storia di Domenico Modugno venerd\u00ec ai Giardini del Portico\",\"datePublished\":\"2014-09-06T21:54:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2014\\\/09\\\/06\\\/la-storia-di-domenico-modugno-venerdi-ai-giardini-del-portico\\\/\"},\"wordCount\":141,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2014\\\/09\\\/06\\\/la-storia-di-domenico-modugno-venerdi-ai-giardini-del-portico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2014\\\/09\\\/questo_sono_io.jpg\",\"articleSection\":[\"Appuntamenti\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2014\\\/09\\\/06\\\/la-storia-di-domenico-modugno-venerdi-ai-giardini-del-portico\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2014\\\/09\\\/06\\\/la-storia-di-domenico-modugno-venerdi-ai-giardini-del-portico\\\/\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2014\\\/09\\\/06\\\/la-storia-di-domenico-modugno-venerdi-ai-giardini-del-portico\\\/\",\"name\":\"La storia di Domenico Modugno venerd\u00ec ai Giardini del Portico - Archivio CassanoWeb\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2014\\\/09\\\/06\\\/la-storia-di-domenico-modugno-venerdi-ai-giardini-del-portico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2014\\\/09\\\/06\\\/la-storia-di-domenico-modugno-venerdi-ai-giardini-del-portico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2014\\\/09\\\/questo_sono_io.jpg\",\"datePublished\":\"2014-09-06T21:54:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2014\\\/09\\\/06\\\/la-storia-di-domenico-modugno-venerdi-ai-giardini-del-portico\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2014\\\/09\\\/06\\\/la-storia-di-domenico-modugno-venerdi-ai-giardini-del-portico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2014\\\/09\\\/06\\\/la-storia-di-domenico-modugno-venerdi-ai-giardini-del-portico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2014\\\/09\\\/questo_sono_io.jpg\",\"contentUrl\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2014\\\/09\\\/questo_sono_io.jpg\",\"width\":320,\"height\":150,\"caption\":\"questo sono io\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/2014\\\/09\\\/06\\\/la-storia-di-domenico-modugno-venerdi-ai-giardini-del-portico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La storia di Domenico Modugno venerd\u00ec ai Giardini del Portico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#website\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/\",\"name\":\"Archivio CassanoWeb\",\"description\":\"La Voce del Paese - un network di idee\",\"publisher\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#organization\",\"name\":\"Archivio CassanoWeb\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/logo-rosso-2.png\",\"contentUrl\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/logo-rosso-2.png\",\"width\":491,\"height\":432,\"caption\":\"Archivio CassanoWeb\"},\"image\":{\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/redazione.cassanoweb\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/#\\\/schema\\\/person\\\/df195bc79a9b4c35127cf005f92e041b\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\"],\"url\":\"https:\\\/\\\/archiviocassano.lavocedelpaese.info\\\/index.php\\\/author\\\/admin_0qgz1xdp\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La storia di Domenico Modugno venerd\u00ec ai Giardini del Portico - Archivio CassanoWeb","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2014\/09\/06\/la-storia-di-domenico-modugno-venerdi-ai-giardini-del-portico\/","og_locale":"it_IT","og_type":"article","og_title":"La storia di Domenico Modugno venerd\u00ec ai Giardini del Portico - Archivio CassanoWeb","og_url":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2014\/09\/06\/la-storia-di-domenico-modugno-venerdi-ai-giardini-del-portico\/","og_site_name":"Archivio CassanoWeb","article_publisher":"https:\/\/www.facebook.com\/redazione.cassanoweb","article_published_time":"2014-09-06T21:54:45+00:00","og_image":[{"width":320,"height":150,"url":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2014\/09\/questo_sono_io.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"admin","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2014\/09\/06\/la-storia-di-domenico-modugno-venerdi-ai-giardini-del-portico\/#article","isPartOf":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2014\/09\/06\/la-storia-di-domenico-modugno-venerdi-ai-giardini-del-portico\/"},"author":{"name":"admin","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#\/schema\/person\/df195bc79a9b4c35127cf005f92e041b"},"headline":"La storia di Domenico Modugno venerd\u00ec ai Giardini del Portico","datePublished":"2014-09-06T21:54:45+00:00","mainEntityOfPage":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2014\/09\/06\/la-storia-di-domenico-modugno-venerdi-ai-giardini-del-portico\/"},"wordCount":141,"commentCount":0,"publisher":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#organization"},"image":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2014\/09\/06\/la-storia-di-domenico-modugno-venerdi-ai-giardini-del-portico\/#primaryimage"},"thumbnailUrl":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2014\/09\/questo_sono_io.jpg","articleSection":["Appuntamenti"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2014\/09\/06\/la-storia-di-domenico-modugno-venerdi-ai-giardini-del-portico\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2014\/09\/06\/la-storia-di-domenico-modugno-venerdi-ai-giardini-del-portico\/","url":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2014\/09\/06\/la-storia-di-domenico-modugno-venerdi-ai-giardini-del-portico\/","name":"La storia di Domenico Modugno venerd\u00ec ai Giardini del Portico - Archivio CassanoWeb","isPartOf":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2014\/09\/06\/la-storia-di-domenico-modugno-venerdi-ai-giardini-del-portico\/#primaryimage"},"image":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2014\/09\/06\/la-storia-di-domenico-modugno-venerdi-ai-giardini-del-portico\/#primaryimage"},"thumbnailUrl":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2014\/09\/questo_sono_io.jpg","datePublished":"2014-09-06T21:54:45+00:00","breadcrumb":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2014\/09\/06\/la-storia-di-domenico-modugno-venerdi-ai-giardini-del-portico\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2014\/09\/06\/la-storia-di-domenico-modugno-venerdi-ai-giardini-del-portico\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2014\/09\/06\/la-storia-di-domenico-modugno-venerdi-ai-giardini-del-portico\/#primaryimage","url":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2014\/09\/questo_sono_io.jpg","contentUrl":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2014\/09\/questo_sono_io.jpg","width":320,"height":150,"caption":"questo sono io"},{"@type":"BreadcrumbList","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/2014\/09\/06\/la-storia-di-domenico-modugno-venerdi-ai-giardini-del-portico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/archiviocassano.lavocedelpaese.info\/"},{"@type":"ListItem","position":2,"name":"La storia di Domenico Modugno venerd\u00ec ai Giardini del Portico"}]},{"@type":"WebSite","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#website","url":"https:\/\/archiviocassano.lavocedelpaese.info\/","name":"Archivio CassanoWeb","description":"La Voce del Paese - un network di idee","publisher":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/archiviocassano.lavocedelpaese.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#organization","name":"Archivio CassanoWeb","url":"https:\/\/archiviocassano.lavocedelpaese.info\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#\/schema\/logo\/image\/","url":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2024\/08\/logo-rosso-2.png","contentUrl":"https:\/\/archiviocassano.lavocedelpaese.info\/wp-content\/uploads\/2024\/08\/logo-rosso-2.png","width":491,"height":432,"caption":"Archivio CassanoWeb"},"image":{"@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/redazione.cassanoweb"]},{"@type":"Person","@id":"https:\/\/archiviocassano.lavocedelpaese.info\/#\/schema\/person\/df195bc79a9b4c35127cf005f92e041b","name":"admin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eabba89a432e8eaa1b0207cc55f7e5340b22712b1ed80677efcf63e02ff5b235?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/archiviocassano.lavocedelpaese.info"],"url":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/author\/admin_0qgz1xdp\/"}]}},"_links":{"self":[{"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/9686","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/comments?post=9686"}],"version-history":[{"count":0,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/9686\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/media\/9685"}],"wp:attachment":[{"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/media?parent=9686"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/categories?post=9686"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/archiviocassano.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/tags?post=9686"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}